{"id":11780,"date":"2023-11-24T05:52:19","date_gmt":"2023-11-24T04:52:19","guid":{"rendered":"https:\/\/swissgliders.ch\/?post_type=product&#038;p=11780"},"modified":"2026-04-28T15:43:53","modified_gmt":"2026-04-28T14:43:53","slug":"woody-valley-x-rated-7","status":"publish","type":"product","link":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/","title":{"rendered":"Woody Valley X-Rated 7"},"content":{"rendered":"<div id=\"imCellStyleGraphics_5\" class=\" translation-block\">\n<p>X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.<\/p>\n<\/div>\n<div><\/div>\n<div class=\" translation-block\">Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.<\/div>\n<div><\/div>\n<div class=\" translation-block\">Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.<\/div>\n<div><\/div>\n<div>inkl. Wasser-Ballastsack<\/div>\n<div>\n<p>\u00abDieses Produkt wird ausschliesslich von einem unserer ausgebildeten Spezialisten mit deinem Gurtzeug bzw. Rettungsschirm kombiniert oder \u00fcber einen von dir gew\u00fcnschten Rettungsschirmpacker SHV ausgeliefert.\u00bb<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>Mehr <a href=\"https:\/\/www.woodyvalley.com\/de\/x-rated-7\/\" target=\"_blank\" rel=\"noopener noreferrer\">Infos<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"excerpt":{"rendered":"<div id=\"imCellStyleGraphics_5\" class=\" translation-block\">\n<p>X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.<\/p>\n<\/div>\n<div><\/div>\n<div class=\" translation-block\">Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.<\/div>\n<div><\/div>\n<div class=\" translation-block\">Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.<\/div>\n<div><\/div>\n<div>inkl. Wasser-Ballastsack<\/div>\n<div>\n<p>\u00abDieses Produkt wird ausschliesslich von einem unserer ausgebildeten Spezialisten mit deinem Gurtzeug bzw. Rettungsschirm kombiniert oder \u00fcber einen von dir gew\u00fcnschten Rettungsschirmpacker SHV ausgeliefert.\u00bb<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>Mehr <a href=\"https:\/\/www.woodyvalley.com\/de\/x-rated-7\/\" target=\"_blank\" rel=\"noopener noreferrer\">Infos<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"featured_media":11782,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[2611],"product_cat":[1041],"product_tag":[999,90],"class_list":{"0":"post-11780","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-woody-valley","7":"product_cat-gleitschirm-liegegurtzeuge","8":"product_tag-liegegurtzeug","9":"product_tag-verkaufsartikel","10":"product_shipping_class-priority-10kg-de","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Woody Valley X-Rated 7 | Gleitschirmschule Thun und Berner Oberland<\/title>\n<meta name=\"description\" content=\"X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Woody Valley X-Rated 7\" \/>\n<meta property=\"og:description\" content=\"X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleitschirmschule Thun und Berner Oberland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissgliders\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T14:43:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissgliders.ch\/wp-content\/uploads\/2023\/11\/WV_Gurtzeug_X-Rated_7-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Swissgliders\" \/>\n<meta name=\"twitter:label1\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/\",\"name\":\"Woody Valley X-Rated 7 | Gleitschirmschule Thun und Berner Oberland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WV_Gurtzeug_X-Rated_7-1.jpg\",\"datePublished\":\"2023-11-24T04:52:19+00:00\",\"dateModified\":\"2026-04-28T14:43:53+00:00\",\"description\":\"X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WV_Gurtzeug_X-Rated_7-1.jpg\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/WV_Gurtzeug_X-Rated_7-1.jpg\",\"width\":1000,\"height\":701,\"caption\":\"WV_Gurtzeug_X-Rated_7-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/woody-valley-x-rated-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/willkommen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gleitschirm Shop\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/gleitschirm-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Woody Valley X-Rated 7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"name\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"description\":\"Gleitschirmschule Thun und Berner Oberland\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\",\"name\":\"Swissgliders Gleitschirmflugschule Thun\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"width\":2500,\"height\":2500,\"caption\":\"Swissgliders Gleitschirmflugschule Thun\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swissgliders\",\"https:\\\/\\\/x.com\\\/Swissgliders\",\"https:\\\/\\\/www.instagram.com\\\/swissgliders\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMCtGdepy9vBhrhX3V_oJOA\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/allgemeine-geschaftsbedingungen\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Woody Valley X-Rated 7 | Gleitschirmschule Thun und Berner Oberland","description":"X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/","og_locale":"de_DE","og_type":"article","og_title":"Woody Valley X-Rated 7","og_description":"X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.","og_url":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/","og_site_name":"Gleitschirmschule Thun und Berner Oberland","article_publisher":"https:\/\/www.facebook.com\/swissgliders","article_modified_time":"2026-04-28T14:43:53+00:00","og_image":[{"width":1000,"height":701,"url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2023\/11\/WV_Gurtzeug_X-Rated_7-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Swissgliders","twitter_misc":{"Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/","url":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/","name":"Woody Valley X-Rated 7 | Gleitschirmschule Thun und Berner Oberland","isPartOf":{"@id":"https:\/\/swissgliders.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/#primaryimage"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/#primaryimage"},"thumbnailUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2023\/11\/WV_Gurtzeug_X-Rated_7-1.jpg","datePublished":"2023-11-24T04:52:19+00:00","dateModified":"2026-04-28T14:43:53+00:00","description":"X-Rated 7 integriert eine breite Palette innovativer Technologien f\u00fcr Handling, Aerodynamik und Komfort, die es zu einem der beliebtesten Gurte auf dem Markt machen.Komplett neu gestaltet, haben wir mit X-Rated7 die heutigen Grenzen \u00fcberwunden und das bisher Unm\u00f6gliche m\u00f6glich gemacht, wobei wir immer auf Ihre Vorschl\u00e4ge geh\u00f6rt haben.Wir haben eure Vorschl\u00e4ge eingebunden und ein perfektes Gleichgewicht zwischen Form und Technik erzielt. Wir haben Eigenschaften entwickelt, auf die du nicht mehr verzichten willst.","breadcrumb":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/#primaryimage","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2023\/11\/WV_Gurtzeug_X-Rated_7-1.jpg","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2023\/11\/WV_Gurtzeug_X-Rated_7-1.jpg","width":1000,"height":701,"caption":"WV_Gurtzeug_X-Rated_7-1"},{"@type":"BreadcrumbList","@id":"https:\/\/swissgliders.ch\/de\/produkt\/woody-valley-x-rated-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swissgliders.ch\/de\/willkommen\/"},{"@type":"ListItem","position":2,"name":"Gleitschirm Shop","item":"https:\/\/swissgliders.ch\/de\/gleitschirm-shop\/"},{"@type":"ListItem","position":3,"name":"Woody Valley X-Rated 7"}]},{"@type":"WebSite","@id":"https:\/\/swissgliders.ch\/de\/#website","url":"https:\/\/swissgliders.ch\/de\/","name":"Gleitschirmschule Thun, Bern, Interlaken","description":"Gleitschirmschule Thun und Berner Oberland","publisher":{"@id":"https:\/\/swissgliders.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissgliders.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swissgliders.ch\/de\/#organization","name":"Swissgliders Gleitschirmflugschule Thun","url":"https:\/\/swissgliders.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","width":2500,"height":2500,"caption":"Swissgliders Gleitschirmflugschule Thun"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swissgliders","https:\/\/x.com\/Swissgliders","https:\/\/www.instagram.com\/swissgliders\/","https:\/\/www.youtube.com\/channel\/UCMCtGdepy9vBhrhX3V_oJOA"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/swissgliders.ch\/de\/allgemeine-geschaftsbedingungen\/"}}]},"og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product\/11780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/comments?post=11780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media\/11782"}],"wp:attachment":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media?parent=11780"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_brand?post=11780"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_cat?post=11780"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_tag?post=11780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}