{"id":12114,"date":"2024-01-14T07:49:35","date_gmt":"2024-01-14T06:49:35","guid":{"rendered":"https:\/\/swissgliders.ch\/?post_type=product&#038;p=12114"},"modified":"2026-04-27T15:16:34","modified_gmt":"2026-04-27T14:16:34","slug":"high-adventure-pizi-touch","status":"publish","type":"product","link":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/","title":{"rendered":"High Adventure Pizi Touch"},"content":{"rendered":"<h3><strong><span class=\"tit\">TRY IT, FLY IT, LOVE IT!<\/span><\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/shop.highadventure.ch\/media\/2483\/catalog\/pizi-touch-1.jpg?size=600\" alt=\"High Adventure Shop | Pizi Touch Gleitschirmhandschuh\" width=\"407\" height=\"431\" \/><\/p>\n<p><span class=\"tit\">Der Pizi ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.<\/span><br \/>\nEin absoluter Hochleister f\u00fcr den Flugsport. Hergestellt mit modernster Technologie aus ausgew\u00e4hlten Hightech-Materialien spielt der Pizi in der absoluten Oberliga. Dank perfekter Passform und Verarbeitung tr\u00e4gt er sich wie eine zweite Haut und erf\u00fcllt beim Groundhandeln, Verstellen der Gurte, Bedienen der Instrumente und am Steuergriff ganze Arbeit. Ein technischer Superstar.<\/p>\n<p>Der Pizi Handschuh bietet alles um vom Fr\u00fchjahr bis im Herbst beim Gleitschirmfliegen ideal vor Wind und Wetter gesch\u00fctzt zu sein. Das robuste Digitalleder und das weiche Softshell Material auf der Oberhand vereinen optimalen Schutz mit h\u00f6chstem Tragekomfort. Beide Materialien sind hydrophobiert worden, sodass der Handschuh wasserabweisende Eigenschaften aufweist. Ein absolutes Highlight des Handschuhs ist das kuschelig weiche und angenehm warme SK Ionix Wollfutter, das ab dem ersten Hineinschl\u00fcpfen, ein wohlig warmes Gef\u00fchl vermittelt und den empfindlichen Pulsbereich w\u00e4rmt und sch\u00fctzt. Das GORE-TEX Infinium<sup>TM<\/sup>\u00a0Futter garantiert 100% Winddichtheit und sorgt f\u00fcr Komfort im Handbereich, bei gleichzeitig maximalem Griffgef\u00fchl. Auf der Oberhand wurde eine Lage Lavalan\u00ae Schafwollisolation eingearbeitet, welche die H\u00e4nde angenehm warm h\u00e4lt. Der Pizi verf\u00fcgt \u00fcber eine am Daumen und Zeigefinger angebrachte Touch Technologie, die das Bedienen<br \/>\nvon Smart Devices erm\u00f6glicht. Der abnehmbare Fangriemen vermeidet ein Verlieren des Handschuhs beim Ausziehen.<\/p>\n<p style=\"text-align: left;\"><strong><span class=\"tit\">Materialaufbau<\/span><\/strong><\/p>\n<table class=\" alignleft\" align=\"center\">\n<tbody>\n<tr>\n<td><\/td>\n<td><strong>Innenhand<\/strong><\/td>\n<td>Ziegenleder hydrophobiert<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Oberhand<\/strong><\/td>\n<td>Softshell , Digital Leder (Ziegenleder), hydrophobiert<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Insulation<\/strong><\/td>\n<td>Lavalan<sup>\u00ae<\/sup>\u00a0Schafwollisolation (Oberhand)<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Insert<\/strong><\/td>\n<td>GORE-TEX Infinium<sup>TM<\/sup>\u00a0Windstopper<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Futter<\/strong><\/td>\n<td>SK Ionix Light Wool<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Features<\/strong><\/td>\n<td>Ergonomische Passform f\u00fcr am Bremsgriff, Touch Technologie, Lederverst\u00e4rkungen, mit Kevlarfaden r\u00fcckstichgesichert vern\u00e4ht, atmungsaktiv, abnehmbare und breiter Fangriemen, waschbar bei 40\u00b0C<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Mehr <a href=\"https:\/\/www.highadventure.ch\/de\/handschuhe-pizi.html\" target=\"_blank\" rel=\"noopener noreferrer\">Info<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"excerpt":{"rendered":"<h3><strong><span class=\"tit\">TRY IT, FLY IT, LOVE IT!<\/span><\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/shop.highadventure.ch\/media\/2483\/catalog\/pizi-touch-1.jpg?size=600\" alt=\"High Adventure Shop | Pizi Touch Gleitschirmhandschuh\" width=\"407\" height=\"431\" \/><\/p>\n<p><span class=\"tit\">Der Pizi ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.<\/span><br \/>\nEin absoluter Hochleister f\u00fcr den Flugsport. Hergestellt mit modernster Technologie aus ausgew\u00e4hlten Hightech-Materialien spielt der Pizi in der absoluten Oberliga. Dank perfekter Passform und Verarbeitung tr\u00e4gt er sich wie eine zweite Haut und erf\u00fcllt beim Groundhandeln, Verstellen der Gurte, Bedienen der Instrumente und am Steuergriff ganze Arbeit. Ein technischer Superstar.<\/p>\n<p>Der Pizi Handschuh bietet alles um vom Fr\u00fchjahr bis im Herbst beim Gleitschirmfliegen ideal vor Wind und Wetter gesch\u00fctzt zu sein. Das robuste Digitalleder und das weiche Softshell Material auf der Oberhand vereinen optimalen Schutz mit h\u00f6chstem Tragekomfort. Beide Materialien sind hydrophobiert worden, sodass der Handschuh wasserabweisende Eigenschaften aufweist. Ein absolutes Highlight des Handschuhs ist das kuschelig weiche und angenehm warme SK Ionix Wollfutter, das ab dem ersten Hineinschl\u00fcpfen, ein wohlig warmes Gef\u00fchl vermittelt und den empfindlichen Pulsbereich w\u00e4rmt und sch\u00fctzt. Das GORE-TEX Infinium<sup>TM<\/sup>\u00a0Futter garantiert 100% Winddichtheit und sorgt f\u00fcr Komfort im Handbereich, bei gleichzeitig maximalem Griffgef\u00fchl. Auf der Oberhand wurde eine Lage Lavalan\u00ae Schafwollisolation eingearbeitet, welche die H\u00e4nde angenehm warm h\u00e4lt. Der Pizi verf\u00fcgt \u00fcber eine am Daumen und Zeigefinger angebrachte Touch Technologie, die das Bedienen<br \/>\nvon Smart Devices erm\u00f6glicht. Der abnehmbare Fangriemen vermeidet ein Verlieren des Handschuhs beim Ausziehen.<\/p>\n<p style=\"text-align: left;\"><strong><span class=\"tit\">Materialaufbau<\/span><\/strong><\/p>\n<table class=\" alignleft\" align=\"center\">\n<tbody>\n<tr>\n<td><\/td>\n<td><strong>Innenhand<\/strong><\/td>\n<td>Ziegenleder hydrophobiert<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Oberhand<\/strong><\/td>\n<td>Softshell , Digital Leder (Ziegenleder), hydrophobiert<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Insulation<\/strong><\/td>\n<td>Lavalan<sup>\u00ae<\/sup>\u00a0Schafwollisolation (Oberhand)<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Insert<\/strong><\/td>\n<td>GORE-TEX Infinium<sup>TM<\/sup>\u00a0Windstopper<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Futter<\/strong><\/td>\n<td>SK Ionix Light Wool<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><strong>Features<\/strong><\/td>\n<td>Ergonomische Passform f\u00fcr am Bremsgriff, Touch Technologie, Lederverst\u00e4rkungen, mit Kevlarfaden r\u00fcckstichgesichert vern\u00e4ht, atmungsaktiv, abnehmbare und breiter Fangriemen, waschbar bei 40\u00b0C<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Mehr <a href=\"https:\/\/www.highadventure.ch\/de\/handschuhe-pizi.html\" target=\"_blank\" rel=\"noopener noreferrer\">Info<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"featured_media":12117,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2022,1947,402],"product_tag":[918,1742,90],"class_list":{"0":"post-12114","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gleitschirm-bekleidung","7":"product_cat-gleitschirm-handschuhe","8":"product_cat-gleitschirm-zubehoer","9":"product_tag-bekleidung","10":"product_tag-handschuhe","11":"product_tag-verkaufsartikel","12":"product_shipping_class-priority-2kg-de","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>High Adventure Pizi Touch | Gleitschirmschule Thun und Berner Oberland<\/title>\n<meta name=\"description\" content=\"Der Pizi Touch ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"High Adventure Pizi Touch\" \/>\n<meta property=\"og:description\" content=\"Der Pizi Touch ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleitschirmschule Thun und Berner Oberland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissgliders\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T14:16:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/01\/HA_Handschuh_Pizi_Touch-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"885\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Swissgliders\" \/>\n<meta name=\"twitter:label1\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/\",\"name\":\"High Adventure Pizi Touch | Gleitschirmschule Thun und Berner Oberland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/HA_Handschuh_Pizi_Touch-1.jpg\",\"datePublished\":\"2024-01-14T06:49:35+00:00\",\"dateModified\":\"2026-04-27T14:16:34+00:00\",\"description\":\"Der Pizi Touch ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/HA_Handschuh_Pizi_Touch-1.jpg\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/HA_Handschuh_Pizi_Touch-1.jpg\",\"width\":1350,\"height\":885,\"caption\":\"HA_Handschuh_Pizi_Touch-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/high-adventure-pizi-touch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/willkommen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gleitschirm Shop\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/gleitschirm-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"High Adventure Pizi Touch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"name\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"description\":\"Gleitschirmschule Thun und Berner Oberland\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\",\"name\":\"Swissgliders Gleitschirmflugschule Thun\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"width\":2500,\"height\":2500,\"caption\":\"Swissgliders Gleitschirmflugschule Thun\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swissgliders\",\"https:\\\/\\\/x.com\\\/Swissgliders\",\"https:\\\/\\\/www.instagram.com\\\/swissgliders\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMCtGdepy9vBhrhX3V_oJOA\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/allgemeine-geschaftsbedingungen\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"High Adventure Pizi Touch | Gleitschirmschule Thun und Berner Oberland","description":"Der Pizi Touch ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/","og_locale":"de_DE","og_type":"article","og_title":"High Adventure Pizi Touch","og_description":"Der Pizi Touch ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.","og_url":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/","og_site_name":"Gleitschirmschule Thun und Berner Oberland","article_publisher":"https:\/\/www.facebook.com\/swissgliders","article_modified_time":"2026-04-27T14:16:34+00:00","og_image":[{"width":1350,"height":885,"url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/01\/HA_Handschuh_Pizi_Touch-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Swissgliders","twitter_misc":{"Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/","url":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/","name":"High Adventure Pizi Touch | Gleitschirmschule Thun und Berner Oberland","isPartOf":{"@id":"https:\/\/swissgliders.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/#primaryimage"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/#primaryimage"},"thumbnailUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/01\/HA_Handschuh_Pizi_Touch-1.jpg","datePublished":"2024-01-14T06:49:35+00:00","dateModified":"2026-04-27T14:16:34+00:00","description":"Der Pizi Touch ist unser 3 Saison-Handschuh f\u00fcr fr\u00fchlingshafte Temperaturen oder den hochalpinen Einsatz auch oberhalb der Nullgradgrenze.","breadcrumb":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/#primaryimage","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/01\/HA_Handschuh_Pizi_Touch-1.jpg","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/01\/HA_Handschuh_Pizi_Touch-1.jpg","width":1350,"height":885,"caption":"HA_Handschuh_Pizi_Touch-1"},{"@type":"BreadcrumbList","@id":"https:\/\/swissgliders.ch\/de\/produkt\/high-adventure-pizi-touch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swissgliders.ch\/de\/willkommen\/"},{"@type":"ListItem","position":2,"name":"Gleitschirm Shop","item":"https:\/\/swissgliders.ch\/de\/gleitschirm-shop\/"},{"@type":"ListItem","position":3,"name":"High Adventure Pizi Touch"}]},{"@type":"WebSite","@id":"https:\/\/swissgliders.ch\/de\/#website","url":"https:\/\/swissgliders.ch\/de\/","name":"Gleitschirmschule Thun, Bern, Interlaken","description":"Gleitschirmschule Thun und Berner Oberland","publisher":{"@id":"https:\/\/swissgliders.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissgliders.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swissgliders.ch\/de\/#organization","name":"Swissgliders Gleitschirmflugschule Thun","url":"https:\/\/swissgliders.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","width":2500,"height":2500,"caption":"Swissgliders Gleitschirmflugschule Thun"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swissgliders","https:\/\/x.com\/Swissgliders","https:\/\/www.instagram.com\/swissgliders\/","https:\/\/www.youtube.com\/channel\/UCMCtGdepy9vBhrhX3V_oJOA"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/swissgliders.ch\/de\/allgemeine-geschaftsbedingungen\/"}}]},"og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product\/12114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/comments?post=12114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media\/12117"}],"wp:attachment":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media?parent=12114"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_brand?post=12114"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_cat?post=12114"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_tag?post=12114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}