{"id":14876,"date":"2024-10-01T09:59:36","date_gmt":"2024-10-01T08:59:36","guid":{"rendered":"https:\/\/swissgliders.ch\/?post_type=product&#038;p=14876"},"modified":"2026-01-14T10:32:15","modified_gmt":"2026-01-14T09:32:15","slug":"niviuk-kargo-urban","status":"publish","type":"product","link":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/","title":{"rendered":"Niviuk Kargo Urban"},"content":{"rendered":"<div class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\">\n<h3 class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\">Kargo Urban<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/boutique.plaine-altitude.com\/14351-large_default\/sac-de-ville-niviuk-kargo-urban.jpg\" width=\"366\" height=\"366\" \/><\/p>\n<div data-aos=\"fade-in\"><\/div>\n<\/div>\n<div class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\">Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.<\/div>\n<div data-aos=\"fade-in\"><\/div>\n<div data-aos=\"fade-in\">\n<div class=\"desplegador\">\n<div class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\"><\/div>\n<div data-aos=\"fade-in\">\n<div class=\"desplegador\">\n<h4><i>Produktdetail <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/i><\/h4>\n<\/div>\n<div class=\"content\"><strong>\u2713 Gemacht f\u00fcr den t\u00e4glichen Gebrauch<\/strong><br \/>\nPerfekt f\u00fcr den schnelllebigen Lebensstil von heute, kombiniert der Kargo Urban die Langlebigkeit und Qualit\u00e4t, den du von einer Marke erwartest, der sich auf Abenteuerausr\u00fcstung spezialisiert hat, mit Funktion und Style f\u00fcr den Gebrauch im Alltag. Egal, ob du zur Arbeit pendelst, zum Unterricht gehst oder einfach nur unterwegs bist, dieser Rucksack bietet dir den Platz und die Organisation, die du brauchst &#8211; ohne Kompromisse im Bezug auf Komfort.<strong>\u2713 Starke und wasserdichte Materialien<\/strong><br \/>\nEr besteht aus P600 TPU-Material auf der Au\u00dfenseite, f\u00fcr au\u00dfergew\u00f6hnliche Haltbarkeit und D70 f\u00fcr die Innentaschen, damit bleibt er gleichzeitig sch\u00f6n leicht. Der obere und untere Teil des Rucksacks sind wasserdicht, so dass deine Sachen jederzeit gesch\u00fctzt sind.<strong>\u2713 Hochwertige Verarbeitung<\/strong><br \/>\nJedes Detail des Kargo Urban wurde entwickelt, um dir einen robusten, qualitativ hochwertigen Rucksack zu bieten. Die sorgf\u00e4ltige Verarbeitung sorgt daf\u00fcr, dass er im t\u00e4glichen Gebrauch den anspruchsvollsten Bedingungen standh\u00e4lt.<strong>\u2713 Verstellbare Tr\u00e4ger<\/strong><br \/>\nMit den verstellbaren Schultergurten kannst du den Rucksack an deine K\u00f6rperl\u00e4nge anpassen \u2013 f\u00fcr optimalen Tragekomfort. Der Brustgurt ist ebenfalls verstellbar und l\u00e4sst sich vertikal an den Schultergurten verschieben. So passt er sich perfekt an die tragende Person an und &#8211; das Gewicht ist gleichm\u00e4\u00dfig verteilt und der Rucksack bleibt fix da, wo du ihn haben willst.<strong>\u2713 Komfort und Ergonomie<\/strong><br \/>\nAirMesh an den Schultergurten und am R\u00fccken sorgt f\u00fcr ausreichende Bel\u00fcftung und \u00fcberragenden Komfort, so dass sich der Rucksack auch im vollen Zustand leicht anf\u00fchlt.<\/p>\n<p><strong>\u2713 Details und Funktionen<\/strong><br \/>\n&#8211; Zwei Lycra-Taschen auf jeder Seite f\u00fcr den Transport von Wasserflaschen oder anderen Gegenst\u00e4nden, auf die man schnell und einfach zugreifen m\u00f6chte.<br \/>\n&#8211; Eine kleine Rei\u00dfverschlusstasche auf der Vorderseite oben bietet sicheren Platz f\u00fcr kleine Wertsachen wie Schl\u00fcssel oder Handy.<br \/>\n&#8211; Die vordere Rei\u00dfverschlusstasche eignet sich perfekt zum Verstauen von Gegenst\u00e4nden, die du h\u00e4ufig brauchst, wie z. B. ein Buch oder Notepad.<br \/>\n&#8211; Der Hauptrei\u00dfverschluss erm\u00f6glicht einen einfachen Zugang zum Inneren des Rucksacks. Dar\u00fcber hinaus l\u00e4sst sich ein Rei\u00dfverschluss auf der Seite des R\u00fcckenteils vertikal \u00f6ffnen und bietet so einen besseren Zugriff, ohne den gesamten Inhalt entleeren zu m\u00fcssen. So kannst du zum Beispiel deinen Laptop ganz einfach herausnehmen, auch wenn der Rucksack voll ist.<br \/>\n&#8211; Im Inneren befindet sich ein Schaumstoff-Trennfach, das speziell f\u00fcr Laptops oder andere elektronische Ger\u00e4te entwickelt wurde, um sie sicher und gesch\u00fctzt zu halten.<br \/>\n&#8211; Eine kleine Netz-Innentasche mit Rei\u00dfverschluss ist ideal f\u00fcr kleine und leicht zu verlierende Gegenst\u00e4nde wie Ladekabel, Schl\u00fcssel oder Speicherkarten.<br \/>\n&#8211; Der Rucksack bietet viele praktische Innen- und Au\u00dfenhaken und -schlaufen, zum fixieren von Accessoires wie Schl\u00fcsselanh\u00e4ngern, Sonnenbrillenetuis oder zus\u00e4tzlicher Ausr\u00fcstung.<br \/>\n&#8211; Eine kleine Innentasche mit Klettverschluss eignet sich perfekt zum Aufbewahren von Dokumenten oder Karten. Er ist auf der R\u00fcckseite leicht versteckt und kann \u00fcber den Rei\u00dfverschluss auf der R\u00fcckseite erreicht werden.<br \/>\n&#8211; Hinterer Gurt zur Befestigung an einem Trolley.<br \/>\n&#8211; Ein Griff an der Oberseite erleichtert das Tragen des Rucksacks mit einer Hand.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content\"><\/div>\n<\/div>\n<div data-aos=\"fade-in\"><\/div>\n<div data-aos=\"fade-in\">\n<table border=\"0\" cellspacing=\"1\" cellpadding=\"5\">\n<tbody>\n<tr>\n<td><strong>Gewicht<\/strong><\/td>\n<td>558 g<\/td>\n<\/tr>\n<tr>\n<td><strong>Volumen\u00a0<\/strong><\/td>\n<td>29 L<\/td>\n<\/tr>\n<tr>\n<td><strong>L\u00e4nge<\/strong><\/td>\n<td>49 cm<\/td>\n<\/tr>\n<tr>\n<td><strong>Breite<\/strong><\/td>\n<td>29 cm<\/td>\n<\/tr>\n<tr>\n<td><strong>Tiefe<\/strong><\/td>\n<td>20 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><br class=\"avia-permanent-lb\" \/>Mehr <a href=\"https:\/\/niviuk.com\/de\/kargo-urban\" target=\"_blank\" rel=\"noopener noreferrer\">Info<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><em>Das k\u00f6nnte dich eventuell auch interessieren<\/em> \ud83d\ude0e<\/p>\n<p>\ud83d\udc49 <a href=\"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-bag\/\">KARGO BAG SERIE<\/a><\/p>\n<p>\ud83d\udc49 <a href=\"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-eco-kargo\/\">ECO KARGO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\">\n<h3 class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\">Kargo Urban<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/boutique.plaine-altitude.com\/14351-large_default\/sac-de-ville-niviuk-kargo-urban.jpg\" width=\"366\" height=\"366\" \/><\/p>\n<div data-aos=\"fade-in\"><\/div>\n<\/div>\n<div class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\">Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.<\/div>\n<div data-aos=\"fade-in\"><\/div>\n<div data-aos=\"fade-in\">\n<div class=\"desplegador\">\n<div class=\"detalls aos-init aos-animate\" data-aos=\"fade-in\"><\/div>\n<div data-aos=\"fade-in\">\n<div class=\"desplegador\">\n<h4><i>Produktdetail <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/i><\/h4>\n<\/div>\n<div class=\"content\"><strong>\u2713 Gemacht f\u00fcr den t\u00e4glichen Gebrauch<\/strong><br \/>\nPerfekt f\u00fcr den schnelllebigen Lebensstil von heute, kombiniert der Kargo Urban die Langlebigkeit und Qualit\u00e4t, den du von einer Marke erwartest, der sich auf Abenteuerausr\u00fcstung spezialisiert hat, mit Funktion und Style f\u00fcr den Gebrauch im Alltag. Egal, ob du zur Arbeit pendelst, zum Unterricht gehst oder einfach nur unterwegs bist, dieser Rucksack bietet dir den Platz und die Organisation, die du brauchst &#8211; ohne Kompromisse im Bezug auf Komfort.<strong>\u2713 Starke und wasserdichte Materialien<\/strong><br \/>\nEr besteht aus P600 TPU-Material auf der Au\u00dfenseite, f\u00fcr au\u00dfergew\u00f6hnliche Haltbarkeit und D70 f\u00fcr die Innentaschen, damit bleibt er gleichzeitig sch\u00f6n leicht. Der obere und untere Teil des Rucksacks sind wasserdicht, so dass deine Sachen jederzeit gesch\u00fctzt sind.<strong>\u2713 Hochwertige Verarbeitung<\/strong><br \/>\nJedes Detail des Kargo Urban wurde entwickelt, um dir einen robusten, qualitativ hochwertigen Rucksack zu bieten. Die sorgf\u00e4ltige Verarbeitung sorgt daf\u00fcr, dass er im t\u00e4glichen Gebrauch den anspruchsvollsten Bedingungen standh\u00e4lt.<strong>\u2713 Verstellbare Tr\u00e4ger<\/strong><br \/>\nMit den verstellbaren Schultergurten kannst du den Rucksack an deine K\u00f6rperl\u00e4nge anpassen \u2013 f\u00fcr optimalen Tragekomfort. Der Brustgurt ist ebenfalls verstellbar und l\u00e4sst sich vertikal an den Schultergurten verschieben. So passt er sich perfekt an die tragende Person an und &#8211; das Gewicht ist gleichm\u00e4\u00dfig verteilt und der Rucksack bleibt fix da, wo du ihn haben willst.<strong>\u2713 Komfort und Ergonomie<\/strong><br \/>\nAirMesh an den Schultergurten und am R\u00fccken sorgt f\u00fcr ausreichende Bel\u00fcftung und \u00fcberragenden Komfort, so dass sich der Rucksack auch im vollen Zustand leicht anf\u00fchlt.<\/p>\n<p><strong>\u2713 Details und Funktionen<\/strong><br \/>\n&#8211; Zwei Lycra-Taschen auf jeder Seite f\u00fcr den Transport von Wasserflaschen oder anderen Gegenst\u00e4nden, auf die man schnell und einfach zugreifen m\u00f6chte.<br \/>\n&#8211; Eine kleine Rei\u00dfverschlusstasche auf der Vorderseite oben bietet sicheren Platz f\u00fcr kleine Wertsachen wie Schl\u00fcssel oder Handy.<br \/>\n&#8211; Die vordere Rei\u00dfverschlusstasche eignet sich perfekt zum Verstauen von Gegenst\u00e4nden, die du h\u00e4ufig brauchst, wie z. B. ein Buch oder Notepad.<br \/>\n&#8211; Der Hauptrei\u00dfverschluss erm\u00f6glicht einen einfachen Zugang zum Inneren des Rucksacks. Dar\u00fcber hinaus l\u00e4sst sich ein Rei\u00dfverschluss auf der Seite des R\u00fcckenteils vertikal \u00f6ffnen und bietet so einen besseren Zugriff, ohne den gesamten Inhalt entleeren zu m\u00fcssen. So kannst du zum Beispiel deinen Laptop ganz einfach herausnehmen, auch wenn der Rucksack voll ist.<br \/>\n&#8211; Im Inneren befindet sich ein Schaumstoff-Trennfach, das speziell f\u00fcr Laptops oder andere elektronische Ger\u00e4te entwickelt wurde, um sie sicher und gesch\u00fctzt zu halten.<br \/>\n&#8211; Eine kleine Netz-Innentasche mit Rei\u00dfverschluss ist ideal f\u00fcr kleine und leicht zu verlierende Gegenst\u00e4nde wie Ladekabel, Schl\u00fcssel oder Speicherkarten.<br \/>\n&#8211; Der Rucksack bietet viele praktische Innen- und Au\u00dfenhaken und -schlaufen, zum fixieren von Accessoires wie Schl\u00fcsselanh\u00e4ngern, Sonnenbrillenetuis oder zus\u00e4tzlicher Ausr\u00fcstung.<br \/>\n&#8211; Eine kleine Innentasche mit Klettverschluss eignet sich perfekt zum Aufbewahren von Dokumenten oder Karten. Er ist auf der R\u00fcckseite leicht versteckt und kann \u00fcber den Rei\u00dfverschluss auf der R\u00fcckseite erreicht werden.<br \/>\n&#8211; Hinterer Gurt zur Befestigung an einem Trolley.<br \/>\n&#8211; Ein Griff an der Oberseite erleichtert das Tragen des Rucksacks mit einer Hand.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content\"><\/div>\n<\/div>\n<div data-aos=\"fade-in\"><\/div>\n<div data-aos=\"fade-in\">\n<table border=\"0\" cellspacing=\"1\" cellpadding=\"5\">\n<tbody>\n<tr>\n<td><strong>Gewicht<\/strong><\/td>\n<td>558 g<\/td>\n<\/tr>\n<tr>\n<td><strong>Volumen\u00a0<\/strong><\/td>\n<td>29 L<\/td>\n<\/tr>\n<tr>\n<td><strong>L\u00e4nge<\/strong><\/td>\n<td>49 cm<\/td>\n<\/tr>\n<tr>\n<td><strong>Breite<\/strong><\/td>\n<td>29 cm<\/td>\n<\/tr>\n<tr>\n<td><strong>Tiefe<\/strong><\/td>\n<td>20 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><br class=\"avia-permanent-lb\" \/>Mehr <a href=\"https:\/\/niviuk.com\/de\/kargo-urban\" target=\"_blank\" rel=\"noopener noreferrer\">Info<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><em>Das k\u00f6nnte dich eventuell auch interessieren<\/em> \ud83d\ude0e<\/p>\n<p>\ud83d\udc49 <a href=\"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-bag\/\">KARGO BAG SERIE<\/a><\/p>\n<p>\ud83d\udc49 <a href=\"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-eco-kargo\/\">ECO KARGO<\/a><\/p>\n","protected":false},"featured_media":14878,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2072],"product_tag":[2210,90],"class_list":{"0":"post-14876","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gleitschirm-rucksaecke","7":"product_tag-rucksack","8":"product_tag-verkaufsartikel","9":"product_shipping_class-priority-2kg-de","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Niviuk Kargo Urban | Gleitschirmschule Thun und Berner Oberland<\/title>\n<meta name=\"description\" content=\"Kargo Urban Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Niviuk Kargo Urban\" \/>\n<meta property=\"og:description\" content=\"Kargo Urban Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleitschirmschule Thun und Berner Oberland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissgliders\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T09:32:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/10\/Niviuk_Rucksack_Kargo-Urban-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"949\" \/>\n\t<meta property=\"og:image:height\" content=\"691\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Swissgliders\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#067;&#072;&#070;&nbsp;60.00 inkl. MwSt.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/\",\"name\":\"Niviuk Kargo Urban | Gleitschirmschule Thun und Berner Oberland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Niviuk_Rucksack_Kargo-Urban-1.jpg\",\"datePublished\":\"2024-10-01T08:59:36+00:00\",\"dateModified\":\"2026-01-14T09:32:15+00:00\",\"description\":\"Kargo Urban Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Niviuk_Rucksack_Kargo-Urban-1.jpg\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Niviuk_Rucksack_Kargo-Urban-1.jpg\",\"width\":949,\"height\":691,\"caption\":\"Niviuk_Rucksack_Kargo Urban-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/niviuk-kargo-urban\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/willkommen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gleitschirm Shop\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/gleitschirm-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Niviuk Kargo Urban\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"name\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"description\":\"Gleitschirmschule Thun und Berner Oberland\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\",\"name\":\"Swissgliders Gleitschirmflugschule Thun\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"width\":2500,\"height\":2500,\"caption\":\"Swissgliders Gleitschirmflugschule Thun\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swissgliders\",\"https:\\\/\\\/x.com\\\/Swissgliders\",\"https:\\\/\\\/www.instagram.com\\\/swissgliders\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMCtGdepy9vBhrhX3V_oJOA\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/allgemeine-geschaftsbedingungen\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"60.00\" \/>\n<meta property=\"product:price:currency\" content=\"CHF\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Niviuk Kargo Urban | Gleitschirmschule Thun und Berner Oberland","description":"Kargo Urban Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/","og_locale":"de_DE","og_type":"article","og_title":"Niviuk Kargo Urban","og_description":"Kargo Urban Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.","og_url":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/","og_site_name":"Gleitschirmschule Thun und Berner Oberland","article_publisher":"https:\/\/www.facebook.com\/swissgliders","article_modified_time":"2026-01-14T09:32:15+00:00","og_image":[{"width":949,"height":691,"url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/10\/Niviuk_Rucksack_Kargo-Urban-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Swissgliders","twitter_misc":{"Preis":"&#67;&#72;&#70;&nbsp;60.00 inkl. MwSt.","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/","url":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/","name":"Niviuk Kargo Urban | Gleitschirmschule Thun und Berner Oberland","isPartOf":{"@id":"https:\/\/swissgliders.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/#primaryimage"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/#primaryimage"},"thumbnailUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/10\/Niviuk_Rucksack_Kargo-Urban-1.jpg","datePublished":"2024-10-01T08:59:36+00:00","dateModified":"2026-01-14T09:32:15+00:00","description":"Kargo Urban Der neue Kargo Urban ist perfekt f\u00fcr deinen Alltag. Auf maximale Funktionalit\u00e4t und Komfort entwickelt, passt er sich ideal an deinen aktiven und dynamischen Lebensstil an. Er ist praktisch und l\u00e4sst sich angenehm tragen, und mit den verschiedenen F\u00e4chern kannst du deine Sachen \u00fcbersichtlich organisieren. Du hast alles griffbereit, was du t\u00e4glich brauchst. Stylisch und vielseitig einsetzbar \u2013 dein perfekter Begleiter f\u00fcr St\u00e4dte- und Wochenendtrips.","breadcrumb":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/#primaryimage","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/10\/Niviuk_Rucksack_Kargo-Urban-1.jpg","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/10\/Niviuk_Rucksack_Kargo-Urban-1.jpg","width":949,"height":691,"caption":"Niviuk_Rucksack_Kargo Urban-1"},{"@type":"BreadcrumbList","@id":"https:\/\/swissgliders.ch\/de\/produkt\/niviuk-kargo-urban\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swissgliders.ch\/de\/willkommen\/"},{"@type":"ListItem","position":2,"name":"Gleitschirm Shop","item":"https:\/\/swissgliders.ch\/de\/gleitschirm-shop\/"},{"@type":"ListItem","position":3,"name":"Niviuk Kargo Urban"}]},{"@type":"WebSite","@id":"https:\/\/swissgliders.ch\/de\/#website","url":"https:\/\/swissgliders.ch\/de\/","name":"Gleitschirmschule Thun, Bern, Interlaken","description":"Gleitschirmschule Thun und Berner Oberland","publisher":{"@id":"https:\/\/swissgliders.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissgliders.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swissgliders.ch\/de\/#organization","name":"Swissgliders Gleitschirmflugschule Thun","url":"https:\/\/swissgliders.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","width":2500,"height":2500,"caption":"Swissgliders Gleitschirmflugschule Thun"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swissgliders","https:\/\/x.com\/Swissgliders","https:\/\/www.instagram.com\/swissgliders\/","https:\/\/www.youtube.com\/channel\/UCMCtGdepy9vBhrhX3V_oJOA"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/swissgliders.ch\/de\/allgemeine-geschaftsbedingungen\/"}}]},"product_price_amount":"60.00","product_price_currency":"CHF","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product\/14876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/comments?post=14876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media\/14878"}],"wp:attachment":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media?parent=14876"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_brand?post=14876"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_cat?post=14876"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_tag?post=14876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}