{"id":18202,"date":"2024-12-27T18:35:58","date_gmt":"2024-12-27T17:35:58","guid":{"rendered":"https:\/\/swissgliders.ch\/?post_type=product&#038;p=18202"},"modified":"2025-05-08T19:30:20","modified_gmt":"2025-05-08T18:30:20","slug":"skywalk-puez-sporty-dry-shirt-women","status":"publish","type":"product","link":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/","title":{"rendered":"Skywalk Puez Sporty Dry Shirt Women"},"content":{"rendered":"<div class=\"properties-name\">\n<div class=\"properties-name\">\n<div class=\"properties-name\">\n<h3>Skywalk Puez Sporty Dry Shirt Women<\/h3>\n<h1 class=\"product--title\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/shop.skywalk.info\/media\/image\/26\/9e\/f2\/SCPSDW1SH-1.png\" width=\"322\" height=\"322\" \/><\/h1>\n<\/div>\n<div>\n<div>\n<p>Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>Farbe: Shadow<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Mehr <a href=\"https:\/\/shop.skywalk.info\/de\/fashion\/shirts\/3746\/puez-sporty-dry-shirt-women?c=348\" target=\"_blank\" rel=\"noopener noreferrer\">Info<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"properties-name\">\n<div class=\"properties-name\">\n<div class=\"properties-name\">\n<h3>Skywalk Puez Sporty Dry Shirt Women<\/h3>\n<h1 class=\"product--title\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/shop.skywalk.info\/media\/image\/26\/9e\/f2\/SCPSDW1SH-1.png\" width=\"322\" height=\"322\" \/><\/h1>\n<\/div>\n<div>\n<div>\n<p>Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>Farbe: Shadow<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Mehr <a href=\"https:\/\/shop.skywalk.info\/de\/fashion\/shirts\/3746\/puez-sporty-dry-shirt-women?c=348\" target=\"_blank\" rel=\"noopener noreferrer\">Info<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"featured_media":18205,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2022],"product_tag":[918],"class_list":{"0":"post-18202","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gleitschirm-bekleidung","7":"product_tag-bekleidung","8":"product_shipping_class-priority-2kg-de","10":"first","11":"instock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Skywalk Puez Sporty Dry Shirt Women | Gleitschirmschule Thun und Berner Oberland<\/title>\n<meta name=\"description\" content=\"Skywalk Puez Sporty Dry Shirt Women Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skywalk Puez Sporty Dry Shirt Women\" \/>\n<meta property=\"og:description\" content=\"Skywalk Puez Sporty Dry Shirt Women Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleitschirmschule Thun und Berner Oberland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissgliders\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T18:30:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/12\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Swissgliders\" \/>\n<meta name=\"twitter:label1\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/\",\"name\":\"Skywalk Puez Sporty Dry Shirt Women | Gleitschirmschule Thun und Berner Oberland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png\",\"datePublished\":\"2024-12-27T17:35:58+00:00\",\"dateModified\":\"2025-05-08T18:30:20+00:00\",\"description\":\"Skywalk Puez Sporty Dry Shirt Women Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png\",\"width\":1400,\"height\":1400,\"caption\":\"Skywalk_T-Shirt_Puez Sporty Dry Shirt Women-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/skywalk-puez-sporty-dry-shirt-women\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/willkommen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gleitschirm Shop\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/gleitschirm-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Skywalk Puez Sporty Dry Shirt Women\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"name\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"description\":\"Gleitschirmschule Thun und Berner Oberland\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\",\"name\":\"Swissgliders Gleitschirmflugschule Thun\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"width\":2500,\"height\":2500,\"caption\":\"Swissgliders Gleitschirmflugschule Thun\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swissgliders\",\"https:\\\/\\\/x.com\\\/Swissgliders\",\"https:\\\/\\\/www.instagram.com\\\/swissgliders\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMCtGdepy9vBhrhX3V_oJOA\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/allgemeine-geschaftsbedingungen\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Skywalk Puez Sporty Dry Shirt Women | Gleitschirmschule Thun und Berner Oberland","description":"Skywalk Puez Sporty Dry Shirt Women Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/","og_locale":"de_DE","og_type":"article","og_title":"Skywalk Puez Sporty Dry Shirt Women","og_description":"Skywalk Puez Sporty Dry Shirt Women Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.","og_url":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/","og_site_name":"Gleitschirmschule Thun und Berner Oberland","article_publisher":"https:\/\/www.facebook.com\/swissgliders","article_modified_time":"2025-05-08T18:30:20+00:00","og_image":[{"width":1400,"height":1400,"url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/12\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Swissgliders","twitter_misc":{"Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/","url":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/","name":"Skywalk Puez Sporty Dry Shirt Women | Gleitschirmschule Thun und Berner Oberland","isPartOf":{"@id":"https:\/\/swissgliders.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/#primaryimage"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/#primaryimage"},"thumbnailUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/12\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png","datePublished":"2024-12-27T17:35:58+00:00","dateModified":"2025-05-08T18:30:20+00:00","description":"Skywalk Puez Sporty Dry Shirt Women Das Puez Sporty Dry T-Shirt ist ein technisches, locker geschnittenes, kurz\u00e4rmliges T-Shirt mit Rundhalsschnitt, das aus 83 Prozent recyceltem Polyester besteht. Das schnelltrocknende 4-Wege-Strech Material sorgt f\u00fcr hohen Tragekomfort und ein hervorragendes Feuchtigkeitsmanagement bei anstrengenden Bergtouren und anderen sommerlichen Outdoor-Aktivit\u00e4ten. Das Material leitet Feuchtigkeit schnell von der Haut ab und garantiert so ein ideales K\u00f6rperklima. Zudem wurde das T-Shirt mit einer geruchshemmenden Ausr\u00fcstung versehen, damit das Funktionsshirt auch nach l\u00e4ngeren Bergtagen keine unangenehmen Ger\u00fcche entwickelt.","breadcrumb":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/#primaryimage","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/12\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/12\/Skywalk_T-Shirt_Puez-Sporty-Dry-Shirt-Women-1.png","width":1400,"height":1400,"caption":"Skywalk_T-Shirt_Puez Sporty Dry Shirt Women-1"},{"@type":"BreadcrumbList","@id":"https:\/\/swissgliders.ch\/de\/produkt\/skywalk-puez-sporty-dry-shirt-women\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swissgliders.ch\/de\/willkommen\/"},{"@type":"ListItem","position":2,"name":"Gleitschirm Shop","item":"https:\/\/swissgliders.ch\/de\/gleitschirm-shop\/"},{"@type":"ListItem","position":3,"name":"Skywalk Puez Sporty Dry Shirt Women"}]},{"@type":"WebSite","@id":"https:\/\/swissgliders.ch\/de\/#website","url":"https:\/\/swissgliders.ch\/de\/","name":"Gleitschirmschule Thun, Bern, Interlaken","description":"Gleitschirmschule Thun und Berner Oberland","publisher":{"@id":"https:\/\/swissgliders.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissgliders.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swissgliders.ch\/de\/#organization","name":"Swissgliders Gleitschirmflugschule Thun","url":"https:\/\/swissgliders.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","width":2500,"height":2500,"caption":"Swissgliders Gleitschirmflugschule Thun"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swissgliders","https:\/\/x.com\/Swissgliders","https:\/\/www.instagram.com\/swissgliders\/","https:\/\/www.youtube.com\/channel\/UCMCtGdepy9vBhrhX3V_oJOA"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/swissgliders.ch\/de\/allgemeine-geschaftsbedingungen\/"}}]},"og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product\/18202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/comments?post=18202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media\/18205"}],"wp:attachment":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media?parent=18202"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_brand?post=18202"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_cat?post=18202"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_tag?post=18202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}