{"id":19971,"date":"2025-06-15T10:13:39","date_gmt":"2025-06-15T09:13:39","guid":{"rendered":"https:\/\/swissgliders.ch\/?post_type=product&#038;p=19971"},"modified":"2025-12-27T09:56:37","modified_gmt":"2025-12-27T08:56:37","slug":"nova-glitch","status":"publish","type":"product","link":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/","title":{"rendered":"Nova Glitch"},"content":{"rendered":"<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<h3 class=\"glider_title\">GLITCH \u2013 No compromises acro flying <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h3>\n<h4>Der GLITCH ist das Ergebnis von mehr als f\u00fcnf Jahren Entwicklung mit Th\u00e9o de Blic. Was mit nahezu unfliegbaren Prototypen begann, hat sich zum vielseitigsten Wettbewerbs-Acro-Schirm entwickelt. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h4>\n<h5 class=\"upper_glider_title\">Vierleiner | Zellen: 55 | Streckung: 5.5 | Gewicht: 4.4 kg \u2013 Gr\u00f6\u00dfe 16 <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h5>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/3\/8\/csm_NOVA_GLITCH_Web_5_a55300dbfa.jpg\" \/><\/p>\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<p><strong>Entwicklung:<\/strong> Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr \/>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/7\/3\/csm_NOVA_GLITCH_Web_2_b1b40bed92.jpg\" \/><\/p>\n<p><strong>Eigenschaften:<\/strong>\u00a0Ein hervorragender Acro-Schirm muss in allen Tricks zuverl\u00e4ssig funktionieren. Besonders gro\u00dfen Wert legte Th\u00e9o auf s\u00e4mtliche Heli-Connections. Der GLITCH besticht in diesen Man\u00f6vern durch Aggressivit\u00e4t, ist aber dennoch einfach zu kontrollieren. Der moderate Bremsdruck war ein weiterer wichtiger Punkt, denn er ist die Voraussetzung f\u00fcr lange Trainings-Sessions, zum Beispiel in Organya \u2013 ein absolutes Muss f\u00fcr Th\u00e9o! <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<hr \/>\n<p><strong>Zielgruppe<\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/2\/2\/csm_NOVA_GLITCH_Web_4_f793358da5.jpg\" \/><\/p>\n<p>Der GLITCH wurde f\u00fcr s\u00e4mtliche Tricks optimiert, die in Acro-Wettbewerben erforderlich sind. Er eignet sich nicht als erster Acro-Gleitschirm. Wenn du grundlegende Heli-Verbindungen wie Sat zu Heli oder Misty zu Heli noch nicht beherrschst, empfehlen wir nicht, diese auf dem GLITCH zu erlernen, da er zu aggressiv ist. Wenn du jedoch bei diesen Tricks sattelfest bist, und beginnst, Man\u00f6ver wie Joker Cork und Cowboy zu fliegen und dich weiterentwickeln m\u00f6chtest, solltest du dir den GLITCH ansehen. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<hr \/>\n<p><strong>Gr\u00f6\u00dfe und Fl\u00e4chenbelastung<\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/5\/e\/csm_NOVA_GLITCH_Web_3_c994d47f50.jpg\" \/><\/p>\n<p>The GLITCH executes all acro tricks (including stall to infinite) with very low wing loading. Thus, you don\u2019t need a smaller glider to perform specific tricks. Don&#8217;t assume that you necessarily must fly the GLITCH smaller than your current glider to advance. Several experienced pilots have enjoyed flying the GLITCH even larger than their previous acro gliders. The enhanced climbing ability in thermals is just one of the many advantages you gain. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<hr \/>\n<h3 class=\"glider_subtitle\">Technische Daten <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h3>\n<div>\n<div class=\"scrollable_table glider_technical_details_table\">\n<table class=\"contenttable\">\n<thead>\n<tr>\n<th><\/th>\n<th><\/th>\n<th>13*<\/th>\n<th>14,5*<\/th>\n<th>16<\/th>\n<th>18<\/th>\n<th>20<\/th>\n<th>22<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Zellenzahl<\/td>\n<td class=\"colspan\" colspan=\"8\">55<\/td>\n<\/tr>\n<tr>\n<td>Projizierte Spannweite<\/td>\n<td>m<\/td>\n<td>6,88<\/td>\n<td>7,27<\/td>\n<td>7,64<\/td>\n<td>8,10<\/td>\n<td>8,54<\/td>\n<td>8,95<\/td>\n<\/tr>\n<tr>\n<td>Projizierte Fl\u00e4che<\/td>\n<td>m\u00b2<\/td>\n<td>11,21<\/td>\n<td>12,50<\/td>\n<td>13,80<\/td>\n<td>15,52<\/td>\n<td>17,24<\/td>\n<td>18,97<\/td>\n<\/tr>\n<tr>\n<td>Projizierte Streckung<\/td>\n<td><\/td>\n<td class=\"colspan\" colspan=\"6\">4,23<\/td>\n<\/tr>\n<tr>\n<td>Ausgelegte Spannweite<\/td>\n<td>m<\/td>\n<td>8,48<\/td>\n<td>8,96<\/td>\n<td>9,41<\/td>\n<td>9,98<\/td>\n<td>10,52<\/td>\n<td>11,04<\/td>\n<\/tr>\n<tr>\n<td>Ausgelegte Fl\u00e4che<\/td>\n<td>m\u00b2<\/td>\n<td>12,98<\/td>\n<td>14,48<\/td>\n<td>15,98<\/td>\n<td>17,98<\/td>\n<td>19,98<\/td>\n<td>21,97<\/td>\n<\/tr>\n<tr>\n<td>Ausgelegte Streckung<\/td>\n<td class=\"colspan\" colspan=\"8\">5,50<\/td>\n<\/tr>\n<tr>\n<td>Abstand Pilot \u2013 Kappe<\/td>\n<td>m<\/td>\n<td>6,26<\/td>\n<td>6,61<\/td>\n<td>6,94<\/td>\n<td>7,36<\/td>\n<td>7,76<\/td>\n<td>8,14<\/td>\n<\/tr>\n<tr>\n<td>Gesamtleinenl\u00e4nge<\/td>\n<td>m<\/td>\n<td>254<\/td>\n<td>269<\/td>\n<td>284<\/td>\n<td>302<\/td>\n<td>319<\/td>\n<td>336<\/td>\n<\/tr>\n<tr>\n<td>Max. Profiltiefe<\/td>\n<td>m<\/td>\n<td>1,91<\/td>\n<td>2,01<\/td>\n<td>2,12<\/td>\n<td>2,25<\/td>\n<td>2,37<\/td>\n<td>2,48<\/td>\n<\/tr>\n<tr>\n<td>Min. Profiltiefe<\/td>\n<td>m<\/td>\n<td>0,47<\/td>\n<td>0,50<\/td>\n<td>0,52<\/td>\n<td>0,56<\/td>\n<td>0,59<\/td>\n<td>0,61<\/td>\n<\/tr>\n<tr>\n<td>Gewicht<\/td>\n<td>kg<\/td>\n<td>3,9<\/td>\n<td>4,2<\/td>\n<td>4,4<\/td>\n<td>4,8<\/td>\n<td>5,2<\/td>\n<td>5,5<\/td>\n<\/tr>\n<tr>\n<td>Max. take off weight \/ Load test<\/td>\n<td>kg<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>130<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p><em>*Gr\u00f6\u00dfen 13 und 14,5 nicht vorr\u00e4tig, nur auf Anfrage<\/em><\/p>\n<h3 class=\"glider_subtitle\">Farben <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h3>\n<div>\n<section id=\"glider_colors\">\n<div class=\"image_caption elements_2\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy-image\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/3\/7\/csm_glitch_red_cdcb323930.png\" alt=\"\" width=\"403\" height=\"211\" \/><strong>ROT\u00a0 \u00a0 <\/strong><img loading=\"lazy\" decoding=\"async\" class=\"lazy-image\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/5\/b\/csm_glitch_blue_81c9023315.png\" alt=\"\" width=\"403\" height=\"211\" \/><strong>BLAU<\/strong><\/div>\n<\/section>\n<\/div>\n<p>&nbsp;<\/p>\n<h3 class=\"glider_subtitle expander-header\">Lieferumfang <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><strong class=\"glider_introduction\" style=\"font-size: 16px;\">NOVA Stuff Sack.<\/strong><\/h3>\n<p style=\"font-size: 16px; font-weight: 400;\">Formsch\u00f6ner, technisch durchdachter Innenpacksack. Dank seiner eckigen Form kann der Schirm darin im gefalteten Zustand gut verstaut werden. Aussparungen am Boden sorgen f\u00fcr eine gute Bel\u00fcftung.<\/p>\n<div class=\"shipment_container expander-content\">\n<section class=\"shipment\"><img loading=\"lazy\" decoding=\"async\" class=\"opacity_hover_js js_enabled\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/e\/7\/csm_NOVA_Stuff_Sack_web_a7d0f59337.png\" alt=\"\" width=\"202\" height=\"202\" \/><span class=\"opacity_hover_js js_enabled hover_span\">\u00a0<\/span>\u00a0<\/section>\n<section class=\"shipment\"><strong class=\"glider_introduction\">NOVA Windsack.<\/strong>Damit du wei\u00dft, woher der Wind kommt, legen wir einen Windsack im NOVA- Design bei. Mit einer L\u00e4nge von rund 80 Zentimetern ist er gro\u00df genug f\u00fcr deinen Startplatz.<\/section>\n<section class=\"shipment\"><img loading=\"lazy\" decoding=\"async\" class=\"opacity_hover_js js_enabled\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/7\/e\/csm_NOVA_windsock_79b9793449.png\" alt=\"\" width=\"228\" height=\"228\" \/><span class=\"opacity_hover_js js_enabled hover_span\">\u00a0<\/span>\u00a0<\/section>\n<section><strong class=\"glider_introduction\">Reparatur-Set.<\/strong>Niemand w\u00fcnscht es sich, aber es kann passieren: Ein Loch oder ein kleiner Riss im Gleitschirm. Zur Behebung kleiner Sch\u00e4den liegt ein farblich passendes oder transparentes Reparaturset bei.<\/section>\n<section class=\"shipment\"><img loading=\"lazy\" decoding=\"async\" class=\"opacity_hover_js js_enabled\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/4\/8\/csm_NOVA_Repair_Kit_2021_quadr_147bf0dd12.png\" alt=\"\" width=\"242\" height=\"242\" \/><span class=\"opacity_hover_js js_enabled hover_span\">\u00a0<\/span>\u00a0<\/section>\n<\/div>\n<p>Mehr<a href=\"https:\/\/www.nova.eu\/de\/gleitschirme\/glitch\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Infos<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<h3 class=\"glider_title\">GLITCH \u2013 No compromises acro flying <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h3>\n<h4>Der GLITCH ist das Ergebnis von mehr als f\u00fcnf Jahren Entwicklung mit Th\u00e9o de Blic. Was mit nahezu unfliegbaren Prototypen begann, hat sich zum vielseitigsten Wettbewerbs-Acro-Schirm entwickelt. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h4>\n<h5 class=\"upper_glider_title\">Vierleiner | Zellen: 55 | Streckung: 5.5 | Gewicht: 4.4 kg \u2013 Gr\u00f6\u00dfe 16 <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h5>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/3\/8\/csm_NOVA_GLITCH_Web_5_a55300dbfa.jpg\" \/><\/p>\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<p><strong>Entwicklung:<\/strong> Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr \/>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/7\/3\/csm_NOVA_GLITCH_Web_2_b1b40bed92.jpg\" \/><\/p>\n<p><strong>Eigenschaften:<\/strong>\u00a0Ein hervorragender Acro-Schirm muss in allen Tricks zuverl\u00e4ssig funktionieren. Besonders gro\u00dfen Wert legte Th\u00e9o auf s\u00e4mtliche Heli-Connections. Der GLITCH besticht in diesen Man\u00f6vern durch Aggressivit\u00e4t, ist aber dennoch einfach zu kontrollieren. Der moderate Bremsdruck war ein weiterer wichtiger Punkt, denn er ist die Voraussetzung f\u00fcr lange Trainings-Sessions, zum Beispiel in Organya \u2013 ein absolutes Muss f\u00fcr Th\u00e9o! <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<hr \/>\n<p><strong>Zielgruppe<\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/2\/2\/csm_NOVA_GLITCH_Web_4_f793358da5.jpg\" \/><\/p>\n<p>Der GLITCH wurde f\u00fcr s\u00e4mtliche Tricks optimiert, die in Acro-Wettbewerben erforderlich sind. Er eignet sich nicht als erster Acro-Gleitschirm. Wenn du grundlegende Heli-Verbindungen wie Sat zu Heli oder Misty zu Heli noch nicht beherrschst, empfehlen wir nicht, diese auf dem GLITCH zu erlernen, da er zu aggressiv ist. Wenn du jedoch bei diesen Tricks sattelfest bist, und beginnst, Man\u00f6ver wie Joker Cork und Cowboy zu fliegen und dich weiterentwickeln m\u00f6chtest, solltest du dir den GLITCH ansehen. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<hr \/>\n<p><strong>Gr\u00f6\u00dfe und Fl\u00e4chenbelastung<\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/5\/e\/csm_NOVA_GLITCH_Web_3_c994d47f50.jpg\" \/><\/p>\n<p>The GLITCH executes all acro tricks (including stall to infinite) with very low wing loading. Thus, you don\u2019t need a smaller glider to perform specific tricks. Don&#8217;t assume that you necessarily must fly the GLITCH smaller than your current glider to advance. Several experienced pilots have enjoyed flying the GLITCH even larger than their previous acro gliders. The enhanced climbing ability in thermals is just one of the many advantages you gain. <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<hr \/>\n<h3 class=\"glider_subtitle\">Technische Daten <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h3>\n<div>\n<div class=\"scrollable_table glider_technical_details_table\">\n<table class=\"contenttable\">\n<thead>\n<tr>\n<th><\/th>\n<th><\/th>\n<th>13*<\/th>\n<th>14,5*<\/th>\n<th>16<\/th>\n<th>18<\/th>\n<th>20<\/th>\n<th>22<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Zellenzahl<\/td>\n<td class=\"colspan\" colspan=\"8\">55<\/td>\n<\/tr>\n<tr>\n<td>Projizierte Spannweite<\/td>\n<td>m<\/td>\n<td>6,88<\/td>\n<td>7,27<\/td>\n<td>7,64<\/td>\n<td>8,10<\/td>\n<td>8,54<\/td>\n<td>8,95<\/td>\n<\/tr>\n<tr>\n<td>Projizierte Fl\u00e4che<\/td>\n<td>m\u00b2<\/td>\n<td>11,21<\/td>\n<td>12,50<\/td>\n<td>13,80<\/td>\n<td>15,52<\/td>\n<td>17,24<\/td>\n<td>18,97<\/td>\n<\/tr>\n<tr>\n<td>Projizierte Streckung<\/td>\n<td><\/td>\n<td class=\"colspan\" colspan=\"6\">4,23<\/td>\n<\/tr>\n<tr>\n<td>Ausgelegte Spannweite<\/td>\n<td>m<\/td>\n<td>8,48<\/td>\n<td>8,96<\/td>\n<td>9,41<\/td>\n<td>9,98<\/td>\n<td>10,52<\/td>\n<td>11,04<\/td>\n<\/tr>\n<tr>\n<td>Ausgelegte Fl\u00e4che<\/td>\n<td>m\u00b2<\/td>\n<td>12,98<\/td>\n<td>14,48<\/td>\n<td>15,98<\/td>\n<td>17,98<\/td>\n<td>19,98<\/td>\n<td>21,97<\/td>\n<\/tr>\n<tr>\n<td>Ausgelegte Streckung<\/td>\n<td class=\"colspan\" colspan=\"8\">5,50<\/td>\n<\/tr>\n<tr>\n<td>Abstand Pilot \u2013 Kappe<\/td>\n<td>m<\/td>\n<td>6,26<\/td>\n<td>6,61<\/td>\n<td>6,94<\/td>\n<td>7,36<\/td>\n<td>7,76<\/td>\n<td>8,14<\/td>\n<\/tr>\n<tr>\n<td>Gesamtleinenl\u00e4nge<\/td>\n<td>m<\/td>\n<td>254<\/td>\n<td>269<\/td>\n<td>284<\/td>\n<td>302<\/td>\n<td>319<\/td>\n<td>336<\/td>\n<\/tr>\n<tr>\n<td>Max. Profiltiefe<\/td>\n<td>m<\/td>\n<td>1,91<\/td>\n<td>2,01<\/td>\n<td>2,12<\/td>\n<td>2,25<\/td>\n<td>2,37<\/td>\n<td>2,48<\/td>\n<\/tr>\n<tr>\n<td>Min. Profiltiefe<\/td>\n<td>m<\/td>\n<td>0,47<\/td>\n<td>0,50<\/td>\n<td>0,52<\/td>\n<td>0,56<\/td>\n<td>0,59<\/td>\n<td>0,61<\/td>\n<\/tr>\n<tr>\n<td>Gewicht<\/td>\n<td>kg<\/td>\n<td>3,9<\/td>\n<td>4,2<\/td>\n<td>4,4<\/td>\n<td>4,8<\/td>\n<td>5,2<\/td>\n<td>5,5<\/td>\n<\/tr>\n<tr>\n<td>Max. take off weight \/ Load test<\/td>\n<td>kg<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>120<\/td>\n<td>130<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p><em>*Gr\u00f6\u00dfen 13 und 14,5 nicht vorr\u00e4tig, nur auf Anfrage<\/em><\/p>\n<h3 class=\"glider_subtitle\">Farben <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h3>\n<div>\n<section id=\"glider_colors\">\n<div class=\"image_caption elements_2\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy-image\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/3\/7\/csm_glitch_red_cdcb323930.png\" alt=\"\" width=\"403\" height=\"211\" \/><strong>ROT\u00a0 \u00a0 <\/strong><img loading=\"lazy\" decoding=\"async\" class=\"lazy-image\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/5\/b\/csm_glitch_blue_81c9023315.png\" alt=\"\" width=\"403\" height=\"211\" \/><strong>BLAU<\/strong><\/div>\n<\/section>\n<\/div>\n<p>&nbsp;<\/p>\n<h3 class=\"glider_subtitle expander-header \">Lieferumfang <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><strong class=\"glider_introduction\" style=\"font-size: 16px;\">NOVA Stuff Sack.<\/strong><\/h3>\n<p style=\"font-size: 16px; font-weight: 400;\">Formsch\u00f6ner, technisch durchdachter Innenpacksack. Dank seiner eckigen Form kann der Schirm darin im gefalteten Zustand gut verstaut werden. Aussparungen am Boden sorgen f\u00fcr eine gute Bel\u00fcftung.<\/p>\n<div class=\"shipment_container expander-content\">\n<section class=\"shipment\"><img loading=\"lazy\" decoding=\"async\" class=\"opacity_hover_js js_enabled\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/e\/7\/csm_NOVA_Stuff_Sack_web_a7d0f59337.png\" alt=\"\" width=\"202\" height=\"202\" \/><span class=\"opacity_hover_js js_enabled hover_span\">\u00a0<\/span>\u00a0<\/section>\n<section class=\"shipment\"><strong class=\"glider_introduction\">NOVA Windsack.<\/strong>Damit du wei\u00dft, woher der Wind kommt, legen wir einen Windsack im NOVA- Design bei. Mit einer L\u00e4nge von rund 80 Zentimetern ist er gro\u00df genug f\u00fcr deinen Startplatz.<\/section>\n<section class=\"shipment\"><img loading=\"lazy\" decoding=\"async\" class=\"opacity_hover_js js_enabled\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/7\/e\/csm_NOVA_windsock_79b9793449.png\" alt=\"\" width=\"228\" height=\"228\" \/><span class=\"opacity_hover_js js_enabled hover_span\">\u00a0<\/span>\u00a0<\/section>\n<section><strong class=\"glider_introduction\">Reparatur-Set.<\/strong>Niemand w\u00fcnscht es sich, aber es kann passieren: Ein Loch oder ein kleiner Riss im Gleitschirm. Zur Behebung kleiner Sch\u00e4den liegt ein farblich passendes oder transparentes Reparaturset bei.<\/section>\n<section class=\"shipment\"><img loading=\"lazy\" decoding=\"async\" class=\"opacity_hover_js js_enabled\" src=\"https:\/\/www.nova.eu\/fileadmin\/_processed_\/4\/8\/csm_NOVA_Repair_Kit_2021_quadr_147bf0dd12.png\" alt=\"\" width=\"242\" height=\"242\" \/><span class=\"opacity_hover_js js_enabled hover_span\">\u00a0<\/span>\u00a0<\/section>\n<\/div>\n<p>Mehr<a href=\"https:\/\/www.nova.eu\/de\/gleitschirme\/glitch\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Infos<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"featured_media":17461,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[86],"product_tag":[917,90],"class_list":{"0":"post-19971","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gleitschirme","7":"product_tag-gleitschirm","8":"product_tag-verkaufsartikel","9":"product_shipping_class-priority-10kg-de","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nova Glitch | Gleitschirmschule Thun und Berner Oberland<\/title>\n<meta name=\"description\" content=\"Nova Gleitschirm Glitch vielseitigster Wettbewerbs-Acro-Schirm. Entwicklung: Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova Glitch\" \/>\n<meta property=\"og:description\" content=\"Nova Gleitschirm Glitch vielseitigster Wettbewerbs-Acro-Schirm. Entwicklung: Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleitschirmschule Thun und Berner Oberland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissgliders\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-27T08:56:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/11\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Swissgliders\" \/>\n<meta name=\"twitter:label1\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/\",\"name\":\"Nova Glitch | Gleitschirmschule Thun und Berner Oberland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg\",\"datePublished\":\"2025-06-15T09:13:39+00:00\",\"dateModified\":\"2025-12-27T08:56:37+00:00\",\"description\":\"Nova Gleitschirm Glitch vielseitigster Wettbewerbs-Acro-Schirm. Entwicklung: Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg\",\"width\":2000,\"height\":1250,\"caption\":\"Ozone_Gleitschirm_Zeolite 2-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/nova-glitch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/willkommen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gleitschirm Shop\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/gleitschirm-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nova Glitch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"name\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"description\":\"Gleitschirmschule Thun und Berner Oberland\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\",\"name\":\"Swissgliders Gleitschirmflugschule Thun\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"width\":2500,\"height\":2500,\"caption\":\"Swissgliders Gleitschirmflugschule Thun\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swissgliders\",\"https:\\\/\\\/x.com\\\/Swissgliders\",\"https:\\\/\\\/www.instagram.com\\\/swissgliders\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMCtGdepy9vBhrhX3V_oJOA\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/allgemeine-geschaftsbedingungen\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nova Glitch | Gleitschirmschule Thun und Berner Oberland","description":"Nova Gleitschirm Glitch vielseitigster Wettbewerbs-Acro-Schirm. Entwicklung: Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/","og_locale":"de_DE","og_type":"article","og_title":"Nova Glitch","og_description":"Nova Gleitschirm Glitch vielseitigster Wettbewerbs-Acro-Schirm. Entwicklung: Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren.","og_url":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/","og_site_name":"Gleitschirmschule Thun und Berner Oberland","article_publisher":"https:\/\/www.facebook.com\/swissgliders","article_modified_time":"2025-12-27T08:56:37+00:00","og_image":[{"width":2000,"height":1250,"url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/11\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Swissgliders","twitter_misc":{"Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/","url":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/","name":"Nova Glitch | Gleitschirmschule Thun und Berner Oberland","isPartOf":{"@id":"https:\/\/swissgliders.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/#primaryimage"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/#primaryimage"},"thumbnailUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/11\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg","datePublished":"2025-06-15T09:13:39+00:00","dateModified":"2025-12-27T08:56:37+00:00","description":"Nova Gleitschirm Glitch vielseitigster Wettbewerbs-Acro-Schirm. Entwicklung: Ebenso, wie ein Top-XC-Pilot von einem leicht zu fliegenden Gleitschirm profitiert, gilt dies auch f\u00fcr einen Top-Acro-Piloten: Obwohl Th\u00e9o de Blic auch mit den ersten Versionen des GLITCH zurechtkam, haben wir weiter daran gearbeitet, das Handling in m\u00f6glichst allen Tricks einfacher zu machen. Nach acht Prototypen und jeweils unz\u00e4hligen Trim-Versionen war Th\u00e9o der Meinung, dass wir den besten Acro-Schirm auf dem Markt entwickelt hatten. Daraufhin bauten wir mehrere GLITCHes f\u00fcr Team-Piloten und Freunde und entschieden nach ihrem \u00fcberw\u00e4ltigend positiven Feedback, den GLITCH in Serie zu produzieren.","breadcrumb":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/#primaryimage","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/11\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2024\/11\/Ozone_Gleitschirm_Zeolite-2-1-1.jpg","width":2000,"height":1250,"caption":"Ozone_Gleitschirm_Zeolite 2-1"},{"@type":"BreadcrumbList","@id":"https:\/\/swissgliders.ch\/de\/produkt\/nova-glitch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swissgliders.ch\/de\/willkommen\/"},{"@type":"ListItem","position":2,"name":"Gleitschirm Shop","item":"https:\/\/swissgliders.ch\/de\/gleitschirm-shop\/"},{"@type":"ListItem","position":3,"name":"Nova Glitch"}]},{"@type":"WebSite","@id":"https:\/\/swissgliders.ch\/de\/#website","url":"https:\/\/swissgliders.ch\/de\/","name":"Gleitschirmschule Thun, Bern, Interlaken","description":"Gleitschirmschule Thun und Berner Oberland","publisher":{"@id":"https:\/\/swissgliders.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissgliders.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swissgliders.ch\/de\/#organization","name":"Swissgliders Gleitschirmflugschule Thun","url":"https:\/\/swissgliders.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","width":2500,"height":2500,"caption":"Swissgliders Gleitschirmflugschule Thun"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swissgliders","https:\/\/x.com\/Swissgliders","https:\/\/www.instagram.com\/swissgliders\/","https:\/\/www.youtube.com\/channel\/UCMCtGdepy9vBhrhX3V_oJOA"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/swissgliders.ch\/de\/allgemeine-geschaftsbedingungen\/"}}]},"og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product\/19971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/comments?post=19971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media\/17461"}],"wp:attachment":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media?parent=19971"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_brand?post=19971"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_cat?post=19971"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_tag?post=19971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}