{"id":20058,"date":"2025-06-17T10:31:15","date_gmt":"2025-06-17T09:31:15","guid":{"rendered":"https:\/\/swissgliders.ch\/?post_type=product&#038;p=20058"},"modified":"2025-06-17T10:56:24","modified_gmt":"2025-06-17T09:56:24","slug":"ozone-zeno-2-en-d","status":"publish","type":"product","link":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/","title":{"rendered":"Ozone Zeno 2 EN-D"},"content":{"rendered":"<div>\n<div class=\"\">\n<div class=\"\">\n<div class=\"titol\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/cdn.sanity.io\/images\/lbhlofgm\/production\/0ff196f0cb3b129ab171271975ac26af8d1c5e28-2400x1260.jpg\" alt=\"Zeno 2 | Ozone Paragliders\" width=\"585\" height=\"307\" \/> <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/div>\n<\/div>\n<\/div>\n<div>\n<h4 data-cy=\"gliders-rating-text\">PERFORMANCE \/ COMPETITION &#8211; EN D<\/h4>\n<\/div>\n<div class=\"\">\n<div class=\"\">\n<div>\n<h4 style=\"text-align: center;\"><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul>\n<li>Derselbe Komfort und dieselbe Benutzerfreundlichkeit<\/li>\n<li><a href=\"https:\/\/swissgliders.ch\/de\/produkt\/ozone-enzo-3-en-ccc\/\">Enzo 3<\/a> Level Geschwindigkeit und Gleiten<\/li>\n<li>V\u00f6llig neues Profil mit erh\u00f6htem CM+ (Reflex)<\/li>\n<li>Neue \u00d6ffnungsposition, mit G-Saiten<\/li>\n<li>Neue Hinterkantenverst\u00e4rkung<\/li>\n<li>Neues widerstandsarmes Leinenmaterial und Tragegurte<br \/>\n<br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/li>\n<\/ul>\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<p>Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research &amp; Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Der Charakter<\/strong><\/h4>\n<p>Unser Hauptaugenmerk war es, den legend\u00e4ren Komfort und die einfache Handhabung des Zenos zu bewahren. Daher verf\u00fcgt der Zeno 2 \u00fcber die gleiche Anzahl an Zellen, die gleiche Streckung und zudem \u00fcber mehr passive Sicherheit \u2013 eine verbesserte Reaktion auf Front- und Seitenklapper.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Leistung<\/strong><\/h4>\n<p>Die neue Technologie des Profils unseres Zeno 2 beinhaltet einen h\u00f6heren Faktor des Pitchmoments (CM+) und mehr r\u00fcckw\u00e4rtige Zellen\u00f6ffnungen. Dieses neue Profil des Fl\u00fcgels erm\u00f6glicht eine deutlich h\u00f6here Spitzengeschwindigkeit, besseres Gleiten und mehr Effizienz \u00fcber den gesamten Geschwindigkeitsbereich hinweg. Mit einer etwas geringeren Trimmgeschwindigkeit und bedeutend mehr H\u00f6chstgeschwindigkeit im Vergleich zum Zeno, zieht er nun hinsichtlich Spitzengeschwindigkeit und Gleiten mit dem Enzo 3 gleich. Seine H\u00f6chstgeschwindigkeit ist hoch, sogar bedeutend h\u00f6her als die des original Zeno (wir haben 7 km\/h mehr gemessen), und nur beim finalen Gleitflug eines Wettkampfs tats\u00e4chlich n\u00f6tig.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Das Gef\u00fchl<\/strong><\/h4>\n<p>insgesamt vermittelt der Zeno 2 verglichen mit dem Zeno etwas mehr Feedback, tut das aber immer auf verst\u00e4ndliche Art und Weise. Er bleibt f\u00fcr Piloten dieser Kategorie immer angenehm und vermittelt Vertrauen. Die versch\u00e4rfte Sinneswahrnehmung macht es einfacher, das Herz der Thermik aufzusp\u00fcren und die Luft zu f\u00fchlen. Eine optimierte Innenstruktur vermittelt ein beeindruckendes Gef\u00fchl von Koh\u00e4sion w\u00e4hrend man in thermischen Turbulenzen steigt. Ein Vorteil der Covid-Verz\u00f6gerungen ist, dass wir dadurch sehr viel Zeit f\u00fcr die Feinabstimmung hatten. Genau so, wie wir es am liebsten m\u00f6gen: die Kurvenresonanz ist pr\u00e4zise und dynamisch, mit mehr Agilit\u00e4t als der Zeno.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Der Start<\/strong><\/h4>\n<p>Ein verbessertes Verhalten und mehr Koh\u00e4sion des Segels sind bereits am Boden bei seinem tadellosen Startverhalten sp\u00fcrbar. Der Zeno 2 f\u00fcllt sich einfach in jeder Position am Boden, sogar bei Nullwind. Der Zeno 2 ist vielleicht mit Ausnahme des Zeolite der Zweileiner, der sich am leichtesten Starten l\u00e4sst.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Der Pilot<\/strong><\/h4>\n<p>Der Zeno 2 wurde speziell f\u00fcr sehr erfahrene XC Piloten entwickelt, die mindestens 100 Stunden im Jahr fliegen, solide SIV Erfahrungen haben, auf XC Rekordjagd sind und Leistung auf Wettkampfniveau brauchen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fcdn.sanity.io%2Fimages%2Flbhlofgm%2Fproduction%2F0bb7f33416deba28de7f7f0fe9563c4e97e7a03c-2500x1667.jpg&amp;w=2048&amp;q=75\" alt=\"Image slider\" width=\"843\" height=\"562\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<h4><\/h4>\n<h4>Spezifikationen <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h4>\n<div class=\"container\">\n<div class=\"specsTable\">\n<div class=\"freeze-table\">\n<div class=\"desktop\">\n<div class=\"specs-table-wrapper\">\n<table>\n<thead>\n<tr>\n<th>Gr\u00f6ssen<\/th>\n<th>XS<\/th>\n<th>S<\/th>\n<th>MS<\/th>\n<th>ML<\/th>\n<th>L<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"\">\n<td>Anzahl der Zellen<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Projizierte Fl\u00e4che (m\u00b2)<\/td>\n<td>16.3<\/td>\n<td>17.7<\/td>\n<td>18.9<\/td>\n<td>20.3<\/td>\n<td>22.2<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Ausgelegte Fl\u00e4che (m\u00b2)<\/td>\n<td>19.4<\/td>\n<td>21<\/td>\n<td>22.5<\/td>\n<td>24.1<\/td>\n<td>26.5<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Projizierte Spannweite (m)<\/td>\n<td>9.1<\/td>\n<td>9.5<\/td>\n<td>9.8<\/td>\n<td>10.2<\/td>\n<td>10.7<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Ausgelegte Spannweite (m)<\/td>\n<td>11.6<\/td>\n<td>12<\/td>\n<td>12.5<\/td>\n<td>12.9<\/td>\n<td>13.5<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Projizierte Streckung<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Ausgelegte Streckung<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Fl\u00fcgeltiefe (m)<\/td>\n<td>2.1<\/td>\n<td>2.19<\/td>\n<td>2.26<\/td>\n<td>2.3<\/td>\n<td>2.46<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Glider Weight (kg)<\/td>\n<td>4.5<\/td>\n<td>4.7<\/td>\n<td>4.92<\/td>\n<td>5.22<\/td>\n<td>5.62<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Gewichtsbereich (kg)<\/td>\n<td>65-80<\/td>\n<td>75-90<\/td>\n<td>85-100<\/td>\n<td>95-110<\/td>\n<td>105-125<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Zulassung<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"specs-table specs-table-note-translation\"><em>*Das Gewicht des Schirms kann je Gr\u00f6\u00dfe wegen m\u00f6glicher geringf\u00fcgiger Abweichungen des verwendeten Tuches um bis zu 50 Gramm variieren.<\/em><\/p>\n<p class=\"specs-table specs-table-notes\"><em>* Pending<\/em><\/p>\n<p>&nbsp;<\/p>\n<h4>FARBEN<\/h4>\n<p><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fos-images.flyozone.com%2Fcdn-cgi%2Fimage%2Fwidth%3D800%2Fhttps%3A%2F%2Fozone-os-images.s3.eu-west-1.amazonaws.com%2Fdesign%2FZN2%2F8369%2FZeno2_RUY%3AW.png&amp;w=256&amp;q=75\" alt=\"RUYW\" width=\"181\" height=\"157\" \/><strong>RUY\/W\u00a0<\/strong> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fos-images.flyozone.com%2Fcdn-cgi%2Fimage%2Fwidth%3D800%2Fhttps%3A%2F%2Fozone-os-images.s3.eu-west-1.amazonaws.com%2Fdesign%2FZN2%2F8368%2FZeno2_LOU-L.png&amp;w=256&amp;q=75\" alt=\"LOUL\" width=\"189\" height=\"150\" \/><strong>LOU\/L<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fos-images.flyozone.com%2Fcdn-cgi%2Fimage%2Fwidth%3D800%2Fhttps%3A%2F%2Fozone-os-images.s3.eu-west-1.amazonaws.com%2Fdesign%2FZN2%2F8370%2FZeno2_YAI%3AY.png&amp;w=256&amp;q=75\" alt=\"YAIY\" width=\"180\" height=\"156\" \/><strong>YAI\/Y<\/strong><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<h4>Lieferumfang<\/h4>\n<div class=\"blockRenderer\"><\/div>\n<div class=\"blockRenderer\">\n<div class=\"blockRenderer\">\n<p>Standardm\u00e4\u00dfig wird unser OZONE mit folgendem Zubeh\u00f6r ausgeliefert:<\/p>\n<p>Spezielles Faltkissen, Concerto leichter Zellenpacksack, Schl\u00fcsselanh\u00e4nger, Flaschen\u00f6ffner, Echtheitszeugnis, 2 wei\u00dfe Klebet\u00fccher und Tragegurtschutz.<\/p>\n<\/div>\n<div class=\"blockRenderer\">\n<p>Vielleicht m\u00f6chtest du deiner Bestellung noch etwas hinzuf\u00fcgen, wie etwa:\u00a0Gleitschirmrucksack, Easy Bag (Schnellpacksack) oder Ozone Kleidung und Accessoires.<\/p>\n<\/div>\n<\/div>\n<p><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/>Mehr <a href=\"https:\/\/flyozone.com\/paragliders\/de\/products\/gliders\/zeno-2?z1=Y&amp;z2=A&amp;z3=I&amp;z4=Y&amp;type=stock#colours\" target=\"_blank\" rel=\"noopener\">Infos<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"excerpt":{"rendered":"<div>\n<div class=\"\">\n<div class=\"\">\n<div class=\"titol\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/cdn.sanity.io\/images\/lbhlofgm\/production\/0ff196f0cb3b129ab171271975ac26af8d1c5e28-2400x1260.jpg\" alt=\"Zeno 2 | Ozone Paragliders\" width=\"585\" height=\"307\" \/> <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/div>\n<\/div>\n<\/div>\n<div>\n<h4 data-cy=\"gliders-rating-text\">PERFORMANCE \/ COMPETITION &#8211; EN D<\/h4>\n<\/div>\n<div class=\"\">\n<div class=\"\">\n<div>\n<h4 style=\"text-align: center;\"><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul>\n<li>Derselbe Komfort und dieselbe Benutzerfreundlichkeit<\/li>\n<li><a href=\"https:\/\/swissgliders.ch\/de\/produkt\/ozone-enzo-3-en-ccc\/\">Enzo 3<\/a> Level Geschwindigkeit und Gleiten<\/li>\n<li>V\u00f6llig neues Profil mit erh\u00f6htem CM+ (Reflex)<\/li>\n<li>Neue \u00d6ffnungsposition, mit G-Saiten<\/li>\n<li>Neue Hinterkantenverst\u00e4rkung<\/li>\n<li>Neues widerstandsarmes Leinenmaterial und Tragegurte<br \/>\n<br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/li>\n<\/ul>\n<div class=\"product-info\" data-cy=\"gliders-product-info\">\n<div class=\"blockRenderer\">\n<div>\n<p>Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research &amp; Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Der Charakter<\/strong><\/h4>\n<p>Unser Hauptaugenmerk war es, den legend\u00e4ren Komfort und die einfache Handhabung des Zenos zu bewahren. Daher verf\u00fcgt der Zeno 2 \u00fcber die gleiche Anzahl an Zellen, die gleiche Streckung und zudem \u00fcber mehr passive Sicherheit \u2013 eine verbesserte Reaktion auf Front- und Seitenklapper.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Leistung<\/strong><\/h4>\n<p>Die neue Technologie des Profils unseres Zeno 2 beinhaltet einen h\u00f6heren Faktor des Pitchmoments (CM+) und mehr r\u00fcckw\u00e4rtige Zellen\u00f6ffnungen. Dieses neue Profil des Fl\u00fcgels erm\u00f6glicht eine deutlich h\u00f6here Spitzengeschwindigkeit, besseres Gleiten und mehr Effizienz \u00fcber den gesamten Geschwindigkeitsbereich hinweg. Mit einer etwas geringeren Trimmgeschwindigkeit und bedeutend mehr H\u00f6chstgeschwindigkeit im Vergleich zum Zeno, zieht er nun hinsichtlich Spitzengeschwindigkeit und Gleiten mit dem Enzo 3 gleich. Seine H\u00f6chstgeschwindigkeit ist hoch, sogar bedeutend h\u00f6her als die des original Zeno (wir haben 7 km\/h mehr gemessen), und nur beim finalen Gleitflug eines Wettkampfs tats\u00e4chlich n\u00f6tig.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Das Gef\u00fchl<\/strong><\/h4>\n<p>insgesamt vermittelt der Zeno 2 verglichen mit dem Zeno etwas mehr Feedback, tut das aber immer auf verst\u00e4ndliche Art und Weise. Er bleibt f\u00fcr Piloten dieser Kategorie immer angenehm und vermittelt Vertrauen. Die versch\u00e4rfte Sinneswahrnehmung macht es einfacher, das Herz der Thermik aufzusp\u00fcren und die Luft zu f\u00fchlen. Eine optimierte Innenstruktur vermittelt ein beeindruckendes Gef\u00fchl von Koh\u00e4sion w\u00e4hrend man in thermischen Turbulenzen steigt. Ein Vorteil der Covid-Verz\u00f6gerungen ist, dass wir dadurch sehr viel Zeit f\u00fcr die Feinabstimmung hatten. Genau so, wie wir es am liebsten m\u00f6gen: die Kurvenresonanz ist pr\u00e4zise und dynamisch, mit mehr Agilit\u00e4t als der Zeno.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Der Start<\/strong><\/h4>\n<p>Ein verbessertes Verhalten und mehr Koh\u00e4sion des Segels sind bereits am Boden bei seinem tadellosen Startverhalten sp\u00fcrbar. Der Zeno 2 f\u00fcllt sich einfach in jeder Position am Boden, sogar bei Nullwind. Der Zeno 2 ist vielleicht mit Ausnahme des Zeolite der Zweileiner, der sich am leichtesten Starten l\u00e4sst.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Der Pilot<\/strong><\/h4>\n<p>Der Zeno 2 wurde speziell f\u00fcr sehr erfahrene XC Piloten entwickelt, die mindestens 100 Stunden im Jahr fliegen, solide SIV Erfahrungen haben, auf XC Rekordjagd sind und Leistung auf Wettkampfniveau brauchen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fcdn.sanity.io%2Fimages%2Flbhlofgm%2Fproduction%2F0bb7f33416deba28de7f7f0fe9563c4e97e7a03c-2500x1667.jpg&amp;w=2048&amp;q=75\" alt=\"Image slider\" width=\"843\" height=\"562\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<h4><\/h4>\n<h4>Spezifikationen <br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/h4>\n<div class=\"container\">\n<div class=\"specsTable\">\n<div class=\"freeze-table\">\n<div class=\"desktop\">\n<div class=\"specs-table-wrapper\">\n<table>\n<thead>\n<tr>\n<th>Gr\u00f6ssen<\/th>\n<th>XS<\/th>\n<th>S<\/th>\n<th>MS<\/th>\n<th>ML<\/th>\n<th>L<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"\">\n<td>Anzahl der Zellen<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<td>78<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Projizierte Fl\u00e4che (m\u00b2)<\/td>\n<td>16.3<\/td>\n<td>17.7<\/td>\n<td>18.9<\/td>\n<td>20.3<\/td>\n<td>22.2<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Ausgelegte Fl\u00e4che (m\u00b2)<\/td>\n<td>19.4<\/td>\n<td>21<\/td>\n<td>22.5<\/td>\n<td>24.1<\/td>\n<td>26.5<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Projizierte Spannweite (m)<\/td>\n<td>9.1<\/td>\n<td>9.5<\/td>\n<td>9.8<\/td>\n<td>10.2<\/td>\n<td>10.7<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Ausgelegte Spannweite (m)<\/td>\n<td>11.6<\/td>\n<td>12<\/td>\n<td>12.5<\/td>\n<td>12.9<\/td>\n<td>13.5<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Projizierte Streckung<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<td>5.1<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Ausgelegte Streckung<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<td>6.9<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Fl\u00fcgeltiefe (m)<\/td>\n<td>2.1<\/td>\n<td>2.19<\/td>\n<td>2.26<\/td>\n<td>2.3<\/td>\n<td>2.46<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Glider Weight (kg)<\/td>\n<td>4.5<\/td>\n<td>4.7<\/td>\n<td>4.92<\/td>\n<td>5.22<\/td>\n<td>5.62<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Gewichtsbereich (kg)<\/td>\n<td>65-80<\/td>\n<td>75-90<\/td>\n<td>85-100<\/td>\n<td>95-110<\/td>\n<td>105-125<\/td>\n<\/tr>\n<tr class=\"\">\n<td>Zulassung<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<td>D<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"specs-table specs-table-note-translation\"><em>*Das Gewicht des Schirms kann je Gr\u00f6\u00dfe wegen m\u00f6glicher geringf\u00fcgiger Abweichungen des verwendeten Tuches um bis zu 50 Gramm variieren.<\/em><\/p>\n<p class=\"specs-table specs-table-notes\"><em>* Pending<\/em><\/p>\n<p>&nbsp;<\/p>\n<h4>FARBEN<\/h4>\n<p><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fos-images.flyozone.com%2Fcdn-cgi%2Fimage%2Fwidth%3D800%2Fhttps%3A%2F%2Fozone-os-images.s3.eu-west-1.amazonaws.com%2Fdesign%2FZN2%2F8369%2FZeno2_RUY%3AW.png&amp;w=256&amp;q=75\" alt=\"RUYW\" width=\"181\" height=\"157\" \/><strong>RUY\/W\u00a0<\/strong> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fos-images.flyozone.com%2Fcdn-cgi%2Fimage%2Fwidth%3D800%2Fhttps%3A%2F%2Fozone-os-images.s3.eu-west-1.amazonaws.com%2Fdesign%2FZN2%2F8368%2FZeno2_LOU-L.png&amp;w=256&amp;q=75\" alt=\"LOUL\" width=\"189\" height=\"150\" \/><strong>LOU\/L<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/flyozone.com\/_next\/image?url=https%3A%2F%2Fos-images.flyozone.com%2Fcdn-cgi%2Fimage%2Fwidth%3D800%2Fhttps%3A%2F%2Fozone-os-images.s3.eu-west-1.amazonaws.com%2Fdesign%2FZN2%2F8370%2FZeno2_YAI%3AY.png&amp;w=256&amp;q=75\" alt=\"YAIY\" width=\"180\" height=\"156\" \/><strong>YAI\/Y<\/strong><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/><\/p>\n<h4>Lieferumfang<\/h4>\n<div class=\"blockRenderer\"><\/div>\n<div class=\"blockRenderer\">\n<div class=\"blockRenderer\">\n<p>Standardm\u00e4\u00dfig wird unser OZONE mit folgendem Zubeh\u00f6r ausgeliefert:<\/p>\n<p>Spezielles Faltkissen, Concerto leichter Zellenpacksack, Schl\u00fcsselanh\u00e4nger, Flaschen\u00f6ffner, Echtheitszeugnis, 2 wei\u00dfe Klebet\u00fccher und Tragegurtschutz.<\/p>\n<\/div>\n<div class=\"blockRenderer\">\n<p>Vielleicht m\u00f6chtest du deiner Bestellung noch etwas hinzuf\u00fcgen, wie etwa:\u00a0Gleitschirmrucksack, Easy Bag (Schnellpacksack) oder Ozone Kleidung und Accessoires.<\/p>\n<\/div>\n<\/div>\n<p><br class=\"avia-permanent-lb\" \/><br class=\"avia-permanent-lb\" \/>Mehr <a href=\"https:\/\/flyozone.com\/paragliders\/de\/products\/gliders\/zeno-2?z1=Y&amp;z2=A&amp;z3=I&amp;z4=Y&amp;type=stock#colours\" target=\"_blank\" rel=\"noopener\">Infos<\/a><\/p>\n<p>Falls dieser Artikel nicht an Lager ist, wird er f\u00fcr dich bestellt. Lieferfrist auf Anfrage.<\/p>\n","protected":false},"featured_media":20066,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[2597],"product_cat":[86],"product_tag":[917,90],"class_list":{"0":"post-20058","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-ozone","7":"product_cat-gleitschirme","8":"product_tag-gleitschirm","9":"product_tag-verkaufsartikel","10":"product_shipping_class-priority-10kg-de","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ozone Zeno 2 EN-D | Gleitschirmschule Thun und Berner Oberland<\/title>\n<meta name=\"description\" content=\"Der Ozone Gleitschirm Zeno 2 derselbe Komfort und dieselbe Benutzerfreundlichkeit. Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research &amp; Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ozone Zeno 2 EN-D\" \/>\n<meta property=\"og:description\" content=\"Der Ozone Gleitschirm Zeno 2 derselbe Komfort und dieselbe Benutzerfreundlichkeit. Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research &amp; Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleitschirmschule Thun und Berner Oberland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissgliders\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T09:56:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissgliders.ch\/wp-content\/uploads\/2025\/06\/Ozone_Gleitschirm_Zeno-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Swissgliders\" \/>\n<meta name=\"twitter:label1\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/\",\"name\":\"Ozone Zeno 2 EN-D | Gleitschirmschule Thun und Berner Oberland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Ozone_Gleitschirm_Zeno-2-1.jpg\",\"datePublished\":\"2025-06-17T09:31:15+00:00\",\"dateModified\":\"2025-06-17T09:56:24+00:00\",\"description\":\"Der Ozone Gleitschirm Zeno 2 derselbe Komfort und dieselbe Benutzerfreundlichkeit. Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research & Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Ozone_Gleitschirm_Zeno-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Ozone_Gleitschirm_Zeno-2-1.jpg\",\"width\":2500,\"height\":1667,\"caption\":\"Ozone_Gleitschirm_Zeno 2-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/ozone-zeno-2-en-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/willkommen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gleitschirm Shop\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/gleitschirm-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ozone Zeno 2 EN-D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"name\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"description\":\"Gleitschirmschule Thun und Berner Oberland\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\",\"name\":\"Swissgliders Gleitschirmflugschule Thun\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"width\":2500,\"height\":2500,\"caption\":\"Swissgliders Gleitschirmflugschule Thun\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swissgliders\",\"https:\\\/\\\/x.com\\\/Swissgliders\",\"https:\\\/\\\/www.instagram.com\\\/swissgliders\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMCtGdepy9vBhrhX3V_oJOA\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/allgemeine-geschaftsbedingungen\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"niviuk-icepeak-x-one-en-ccc-2-1\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ozone Zeno 2 EN-D | Gleitschirmschule Thun und Berner Oberland","description":"Der Ozone Gleitschirm Zeno 2 derselbe Komfort und dieselbe Benutzerfreundlichkeit. Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research & Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/","og_locale":"de_DE","og_type":"article","og_title":"Ozone Zeno 2 EN-D","og_description":"Der Ozone Gleitschirm Zeno 2 derselbe Komfort und dieselbe Benutzerfreundlichkeit. Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research & Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.","og_url":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/","og_site_name":"Gleitschirmschule Thun und Berner Oberland","article_publisher":"https:\/\/www.facebook.com\/swissgliders","article_modified_time":"2025-06-17T09:56:24+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2025\/06\/Ozone_Gleitschirm_Zeno-2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Swissgliders","twitter_misc":{"Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/","url":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/","name":"Ozone Zeno 2 EN-D | Gleitschirmschule Thun und Berner Oberland","isPartOf":{"@id":"https:\/\/swissgliders.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/#primaryimage"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/#primaryimage"},"thumbnailUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2025\/06\/Ozone_Gleitschirm_Zeno-2-1.jpg","datePublished":"2025-06-17T09:31:15+00:00","dateModified":"2025-06-17T09:56:24+00:00","description":"Der Ozone Gleitschirm Zeno 2 derselbe Komfort und dieselbe Benutzerfreundlichkeit. Seit vielen Jahren steht der Zeno an der Spitze der EN D Klasse, und uns war klar, dass er nicht einfach zu ersetzen sein w\u00fcrde. Aber nach zwei Jahren intensiver Research & Design Arbeit haben wir nun einen w\u00fcrdigen Nachfolger entwickelt.","breadcrumb":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/#primaryimage","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2025\/06\/Ozone_Gleitschirm_Zeno-2-1.jpg","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2025\/06\/Ozone_Gleitschirm_Zeno-2-1.jpg","width":2500,"height":1667,"caption":"Ozone_Gleitschirm_Zeno 2-1"},{"@type":"BreadcrumbList","@id":"https:\/\/swissgliders.ch\/de\/produkt\/ozone-zeno-2-en-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swissgliders.ch\/de\/willkommen\/"},{"@type":"ListItem","position":2,"name":"Gleitschirm Shop","item":"https:\/\/swissgliders.ch\/de\/gleitschirm-shop\/"},{"@type":"ListItem","position":3,"name":"Ozone Zeno 2 EN-D"}]},{"@type":"WebSite","@id":"https:\/\/swissgliders.ch\/de\/#website","url":"https:\/\/swissgliders.ch\/de\/","name":"Gleitschirmschule Thun, Bern, Interlaken","description":"Gleitschirmschule Thun und Berner Oberland","publisher":{"@id":"https:\/\/swissgliders.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissgliders.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swissgliders.ch\/de\/#organization","name":"Swissgliders Gleitschirmflugschule Thun","url":"https:\/\/swissgliders.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","width":2500,"height":2500,"caption":"Swissgliders Gleitschirmflugschule Thun"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swissgliders","https:\/\/x.com\/Swissgliders","https:\/\/www.instagram.com\/swissgliders\/","https:\/\/www.youtube.com\/channel\/UCMCtGdepy9vBhrhX3V_oJOA"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/swissgliders.ch\/de\/allgemeine-geschaftsbedingungen\/"}}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"niviuk-icepeak-x-one-en-ccc-2-1","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product\/20058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/comments?post=20058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media\/20066"}],"wp:attachment":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media?parent=20058"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_brand?post=20058"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_cat?post=20058"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_tag?post=20058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}