{"id":3423,"date":"2019-11-30T16:20:10","date_gmt":"2019-11-30T15:20:10","guid":{"rendered":"https:\/\/swissgliders.ch\/?post_type=product&#038;p=3423"},"modified":"2024-11-23T20:03:49","modified_gmt":"2024-11-23T19:03:49","slug":"gleitschirm-schnuppertag","status":"publish","type":"product","link":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/","title":{"rendered":"Gutschein Gleitschirm-Schnuppertag"},"content":{"rendered":"<p>Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich!<\/p>\n<p>Auch als Gutschein oder Firmenevent f\u00fcr Team-Buildings ist dies eine super Idee.<\/p>\n<p><a href=\"https:\/\/swissgliders.ch\/de\/ausbildung\/#schnupperkurs\">Mehr Infos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich!<\/p>\n<p>Auch als Gutschein oder Firmenevent f\u00fcr Team-Buildings ist dies eine super Idee.<\/p>\n","protected":false},"featured_media":7822,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2099],"product_tag":[682,681,90],"class_list":{"0":"post-3423","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gleitschirm-geschenke","7":"product_tag-ausbildung","8":"product_tag-schnuppertag","9":"product_tag-verkaufsartikel","10":"product_shipping_class-kostenlos","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gutschein Gleitschirm-Schnuppertag | Gleitschirmschule Thun, Bern, Interlaken<\/title>\n<meta name=\"description\" content=\"Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gutschein Gleitschirm-Schnuppertag\" \/>\n<meta property=\"og:description\" content=\"Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleitschirmschule Thun, Bern, Interlaken\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissgliders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-23T19:03:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/11\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Swissgliders\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#067;&#072;&#070;&nbsp;100.00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/\",\"name\":\"Gutschein Gleitschirm-Schnuppertag | Gleitschirmschule Thun, Bern, Interlaken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg\",\"datePublished\":\"2019-11-30T15:20:10+00:00\",\"dateModified\":\"2024-11-23T19:03:49+00:00\",\"description\":\"Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg\",\"width\":1536,\"height\":2048,\"caption\":\"Swissgliders_Gutschein_Schnuppertag_Kat.Geschenke-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/produkt\\\/gleitschirm-schnuppertag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/willkommen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gleitschirm Shop\",\"item\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/gleitschirm-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gutschein Gleitschirm-Schnuppertag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"name\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"description\":\"Gleitschirmschule Thun, Bern, Interlaken\",\"publisher\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#organization\",\"name\":\"Swissgliders Gleitschirmflugschule Thun\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"contentUrl\":\"https:\\\/\\\/swissgliders.ch\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/swissgliders-logo-rgb-square-L-no-ch-01.png\",\"width\":2500,\"height\":2500,\"caption\":\"Swissgliders Gleitschirmflugschule Thun\"},\"image\":{\"@id\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swissgliders\",\"https:\\\/\\\/x.com\\\/Swissgliders\",\"https:\\\/\\\/www.instagram.com\\\/swissgliders\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMCtGdepy9vBhrhX3V_oJOA\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/swissgliders.ch\\\/de\\\/allgemeine-geschaftsbedingungen\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"100.00\" \/>\n<meta property=\"product:price:currency\" content=\"CHF\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gutschein Gleitschirm-Schnuppertag | Gleitschirmschule Thun, Bern, Interlaken","description":"Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/","og_locale":"de_DE","og_type":"article","og_title":"Gutschein Gleitschirm-Schnuppertag","og_description":"Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich.","og_url":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/","og_site_name":"Gleitschirmschule Thun, Bern, Interlaken","article_publisher":"https:\/\/www.facebook.com\/swissgliders","article_modified_time":"2024-11-23T19:03:49+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/11\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Swissgliders","twitter_misc":{"Preis":"&#67;&#72;&#70;&nbsp;100.00","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/","url":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/","name":"Gutschein Gleitschirm-Schnuppertag | Gleitschirmschule Thun, Bern, Interlaken","isPartOf":{"@id":"https:\/\/swissgliders.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/#primaryimage"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/#primaryimage"},"thumbnailUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/11\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg","datePublished":"2019-11-30T15:20:10+00:00","dateModified":"2024-11-23T19:03:49+00:00","description":"Wenn du am Gleitschirmfliegen interessiert bist aber nicht genau weisst was dich erwartet, ist ein Schnuppertag genau das Richtige f\u00fcr dich.","breadcrumb":{"@id":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/#primaryimage","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/11\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/11\/Gutschein_Schnuppertag_Kat.Geschenke-1.jpg","width":1536,"height":2048,"caption":"Swissgliders_Gutschein_Schnuppertag_Kat.Geschenke-1"},{"@type":"BreadcrumbList","@id":"https:\/\/swissgliders.ch\/de\/produkt\/gleitschirm-schnuppertag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swissgliders.ch\/de\/willkommen\/"},{"@type":"ListItem","position":2,"name":"Gleitschirm Shop","item":"https:\/\/swissgliders.ch\/de\/gleitschirm-shop\/"},{"@type":"ListItem","position":3,"name":"Gutschein Gleitschirm-Schnuppertag"}]},{"@type":"WebSite","@id":"https:\/\/swissgliders.ch\/de\/#website","url":"https:\/\/swissgliders.ch\/de\/","name":"Gleitschirmschule Thun, Bern, Interlaken","description":"Gleitschirmschule Thun, Bern, Interlaken","publisher":{"@id":"https:\/\/swissgliders.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissgliders.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swissgliders.ch\/de\/#organization","name":"Swissgliders Gleitschirmflugschule Thun","url":"https:\/\/swissgliders.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","contentUrl":"https:\/\/swissgliders.ch\/wp-content\/uploads\/2019\/12\/swissgliders-logo-rgb-square-L-no-ch-01.png","width":2500,"height":2500,"caption":"Swissgliders Gleitschirmflugschule Thun"},"image":{"@id":"https:\/\/swissgliders.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swissgliders","https:\/\/x.com\/Swissgliders","https:\/\/www.instagram.com\/swissgliders\/","https:\/\/www.youtube.com\/channel\/UCMCtGdepy9vBhrhX3V_oJOA"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/swissgliders.ch\/de\/allgemeine-geschaftsbedingungen\/"}}]},"product_price_amount":"100.00","product_price_currency":"CHF","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product\/3423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/comments?post=3423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media\/7822"}],"wp:attachment":[{"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/media?parent=3423"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_brand?post=3423"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_cat?post=3423"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swissgliders.ch\/de\/wp-json\/wp\/v2\/product_tag?post=3423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}